{"id":14639,"date":"2025-05-29T13:24:15","date_gmt":"2025-05-29T10:24:15","guid":{"rendered":"https:\/\/www.fmsdocumentation.com\/api-za-povijest-koordinata-objekata-v3\/"},"modified":"2025-05-29T13:27:55","modified_gmt":"2025-05-29T10:27:55","slug":"api-za-povijest-koordinata-objekata-v3","status":"publish","type":"page","link":"https:\/\/www.fmsdocumentation.com\/hr\/apis\/api-za-povijest-koordinata-objekata-v3\/","title":{"rendered":"API za povijest koordinata objekata v3"},"content":{"rendered":"\n<p><p class=\"note\">Bilje\u0161ka<br\/><strong>Ovaj API nije uklju\u010den ni u jedan plan. Obratite se svom voditelju prodaje kako biste naru\u010dili i omogu\u0107ili ovaj API. <\/strong><\/p><\/p>\n\n<p>Idi na odjeljke unutar ove stranice:<\/p>\n\n<ul class=\"wp-block-list\"><li><a href=\"#specific-date-and-time\" data-type=\"internal\" data-id=\"#specific-date-and-time\">Zahtjev za podatke za odre\u0111eni datum i vrijeme<\/a><\/li><li><a href=\"#specific-period\" data-type=\"internal\" data-id=\"#specific-period\">Zahtjev za podatke za odre\u0111eno razdoblje<\/a><\/li><li><a href=\"#tpms-data-support\" data-type=\"internal\" data-id=\"#tpms-data-support\">Podr\u0161ka za TPMS podatke<\/a><\/li><\/ul>\n\n<p>API za povijest koordinata objekata koristi se za ispis povijesnih podataka (koordinata, parametara itd.) objekta. Ovaj API je sli\u010dan <a href=\"https:\/\/www.fmsdocumentation.com\/apis\/object-coordinates-history-api-v2\/\">API-ju za povijest koordinata objekata v2<\/a> , ali v3 tako\u0111er ima novo polje za adresu. Ovaj API ima dvije krajnje to\u010dke, stoga postoje dvije vrste zahtjeva:  <\/p>\n\n<ol class=\"wp-block-list\"><li>Zahtjev za podacima o objektu za odre\u0111eni datum i vrijeme. Prikazuju se samo podaci snimljeni na odre\u0111eni datum i vrijeme. <\/li><li>Zahtjev za podacima o objektu za odre\u0111eno razdoblje. Prikazuju se svi podaci snimljeni tijekom odre\u0111enog razdoblja. <\/li><\/ol>\n\n<h2 class=\"wp-block-heading\" id=\"specific-date-and-time\">Zahtjev za podatke za odre\u0111eni datum i vrijeme<\/h2>\n\n<p>Struktura zahtjeva:<\/p>\n\n<p style=\"background-color: #000000; color: #bbbdc0; font-family: Consolas; padding-left: 10px; padding-right: 10px;\">\n<br\/>\nGET \/objects\/{objectId}\/coordinates\/{datetime}?version=3&#038;api_key=<..>&#038;include_geozones=<...>&#038;include_tire_parameters=<...> HTTP\/1.1 <br\/>\nHost: api.fm-track.com <br\/>\nContent-Type: application\/json;charset=UTF-8 <br\/>\n<br\/>\n<\/p>\n\n<p>Parametri zahtjeva:<\/p>\n\n\n<table id=\"tablepress-176\" class=\"tablepress tablepress-id-176\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Parameter<\/th><th class=\"column-2\">Type<\/th><th class=\"column-3\">Description<\/th><th class=\"column-4\">Required<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">object_id<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">External object ID<\/td><td class=\"column-4\">Yes<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">datetime<\/td><td class=\"column-2\">Date time<\/td><td class=\"column-3\">Specified date and time. Date and time format example: \u201c2019-04-17T11:58:48.090Z\u201d  in accordance to the ISO-8601 standard<\/td><td class=\"column-4\">Yes<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">version<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">API version<\/td><td class=\"column-4\">Yes<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">api_key<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">User identification key<\/td><td class=\"column-4\">Yes<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">include_geozones<\/td><td class=\"column-2\">boolean<\/td><td class=\"column-3\">If true geozones information in the answer will be returned\t<\/td><td class=\"column-4\">No<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">include_tire_parameters<\/td><td class=\"column-2\">boolean<\/td><td class=\"column-3\">If true information about tire pressure in the answer will be returned<\/td><td class=\"column-4\">No<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-176 from cache -->\n\n<p>Primjer odgovora:<\/p>\n\n<div class=\"wp-block-codemirror-blocks-code-block code-block\"><pre class=\"CodeMirror\" data-setting=\"{&quot;mode&quot;:&quot;javascript&quot;,&quot;mime&quot;:&quot;application\/json&quot;,&quot;theme&quot;:&quot;dracula&quot;,&quot;lineNumbers&quot;:true,&quot;styleActiveLine&quot;:false,&quot;lineWrapping&quot;:false,&quot;readOnly&quot;:true,&quot;translatedWithWPMLTM&quot;:&quot;1&quot;,&quot;language&quot;:&quot;JSON&quot;,&quot;modeName&quot;:&quot;json&quot;}\">{\n    \"object_id\":\"abc123\",\n    \"datetime\":\"2019-02-11T02:00:00.000Z\",\n    \"ignition_status\":\"OFF\",\n    \"position\":{\n        \"altitude\" : 0,\n        \"direction\" : 0,\n        \"latitude\" : 0,\n        \"longitude\" : 0,\n        \"satellites_count\" : 0,\n        \"speed\" : 0\n    },\n    \"address\": {\n        \"country\": \"Poland\",\n        \"country_code\": \"PL\",\n        \"county\": \"Wojew\u00f3dztwo dolno\u015bl\u0105skie\",\n        \"region\": \"\",\n        \"locality\": \"\",\n        \"street\": \"E67\",\n        \"house_number\": \"\",\n        \"zip\": \"55\"\n    },\n    \"inputs\":{\n        \"other\":{\n            \"virtual_gps_odometer\":0.0000,\n            \"country_code_geonames\":91\n        },\n        \"device_inputs\":{\n            \"virtual_odometer\":5.00,\n            \"digital_input_4\":false,\n            \"driver_1_state\":\"DRIVE\",\n            \"input_trigger\":0,\n            \"tco_first_driver_state\":\"DRIVE\",\n            \"priority\":\"LOW\",\n            ....,\n            \"hdop\":\"0.0\"\n        },\n        \"calculated_inputs\":{\n            \"din4_working_time\":0.00,\n            \"custom_input_3\":0.00,\n            \"custom_input_6\":0.00,\n            \"temperature\":0.00,\n            \"custom_input_1\":0.00,\n            ....,\n            \"custom_input_2\":0.00,\n            \"mileage\":5000.00\n    \t},\n  \t\t\"geozone_ids\": [\n      \t\t\"0d5d7bc2\",\n          \t\"0d5d7bc2\"\n        \t],\n      \t\"tires\": {\n            \"tire01\": {\n              \"tire_pressure_threshold_detection\": \"2\",\n              \"tire_sensor_electrical_fault\": \"2\",\n              \"tire_status\": \"1\",\n              \"tire_temperature\": \"39.5\",\n              \"tire_air_leakage_rate\": \"2001.0\",\n              \"tire_pressure\": \"400\",\n              \"tire_sensor_enable_status\": \"0\",\n              \"tire_location\": \"23\",\n              \"tire_extended_tire_pressure_support\": \"3\"\n            },\n            ....,\n            \"tire36\": {\n              \"tire_pressure_threshold_detection\": \"2\",\n              \"tire_sensor_electrical_fault\": \"2\",\n              \"tire_status\": \"1\",\n              \"tire_temperature\": \"39.5\",\n              \"tire_air_leakage_rate\": \"2036.0\",\n              \"tire_pressure\": \"400\",\n              \"tire_sensor_enable_status\": \"0\",\n              \"tire_location\": \"23\",\n              \"tire_extended_tire_pressure_support\": \"3\"\n            }\n         },\n   .....\n}<\/pre><\/div>\n\n<p><br\/>Ako je parametar neto\u010dno unesen, sustav \u0107e odgovoriti kodom pogre\u0161ke. Svi kodovi pogre\u0161aka opisani su u odjeljku <a href=\"https:\/\/www.fmsdocumentation.com\/apis\/\">API-ji<\/a> . Parametri za koje nisu navedeni podaci nisu uklju\u010deni u odgovor. Potpuni popis parametara odgovora dostupan je na kraju ovog odjeljka.   <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"specific-period\">Zahtjev za podatke za odre\u0111eno razdoblje<\/h2>\n\n<p>Struktura zahtjeva:<\/p>\n\n<p style=\"background-color: #000000; color: #bbbdc0; font-family: Consolas; padding-left: 10px; padding-right: 10px;\">\n<br\/>\nGET \/objects\/{objectId}\/coordinates?version=3&#038;from_datetime=<..>&#038;to_datetime=<..>&#038;continuation_token=<..>&#038;limit=<..>&#038;api_key=<..>&#038;include_geozones=<...>&#038;include_tire_parameters=<...> HTTP\/1.1 <br\/>\nHost: api.fm-track.com <br\/>\nContent-Type: application\/json;charset=UTF-8 <br\/>\n<br\/>\n<\/p>\n\n<p>Parametri zahtjeva:<\/p>\n\n\n<table id=\"tablepress-177\" class=\"tablepress tablepress-id-177\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Parameter<\/th><th class=\"column-2\">Type<\/th><th class=\"column-3\">Description<\/th><th class=\"column-4\">Required<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">objectId<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">External object ID<\/td><td class=\"column-4\">Yes<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">from_datetime<\/td><td class=\"column-2\">Date time<\/td><td class=\"column-3\">Finds records starting from the specified date and time.  Date and time format example: \u201c2017-04-13T06:58:48.090Z\u201d<\/td><td class=\"column-4\">Yes<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">to_datetime<\/td><td class=\"column-2\">Date time<\/td><td class=\"column-3\">Finds records ending at the specified date and time. Date and time format example: \u201c2017-04-13T06:58:48.090Z\u201d<\/td><td class=\"column-4\">No<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">continuation_token<\/td><td class=\"column-2\">Date time<\/td><td class=\"column-3\">Displays from what date and time the data is shown if the record limit was reached.<\/td><td class=\"column-4\">No<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">limit<\/td><td class=\"column-2\">Integer<\/td><td class=\"column-3\">How many records will be included in the response (default value - 100 records, maximum value - 1000 records).<\/td><td class=\"column-4\">No<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">version<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">API version<\/td><td class=\"column-4\">Yes<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">api_key<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">User identification key<\/td><td class=\"column-4\">Yes<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">include_geozones<\/td><td class=\"column-2\">boolean<\/td><td class=\"column-3\">If true geozones information in the answer will be returned\t<\/td><td class=\"column-4\">No<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">include_tire_parameters<\/td><td class=\"column-2\">boolean<\/td><td class=\"column-3\">If true information about tire pressure in the answer will be returned<\/td><td class=\"column-4\">No<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-177 from cache -->\n\n<p>Primjer odgovora:<\/p>\n\n<div class=\"wp-block-codemirror-blocks-code-block code-block\"><pre class=\"CodeMirror\" data-setting=\"{&quot;mode&quot;:&quot;javascript&quot;,&quot;mime&quot;:&quot;application\/json&quot;,&quot;theme&quot;:&quot;dracula&quot;,&quot;lineNumbers&quot;:true,&quot;styleActiveLine&quot;:false,&quot;lineWrapping&quot;:false,&quot;readOnly&quot;:true,&quot;translatedWithWPMLTM&quot;:&quot;1&quot;,&quot;language&quot;:&quot;JSON&quot;,&quot;modeName&quot;:&quot;json&quot;}\">{\n  \"continuation_token\": \"2017-04-13T06:58:48.121Z\",\n  \"items\": [\n{\n \n    \"object_id\":\"abc123\",\n    \"datetime\":\"2019-02-11T02:00:00.000Z\",\n    \"ignition_status\":\"OFF\",\n    \"business_or_private\":\"BUSINESS\",\n    \"position\":{\n        \"altitude\" : 0,\n        \"direction\" : 0,\n        \"latitude\" : 0,\n        \"longitude\" : 0,\n        \"satellites_count\" : 0,\n        \"speed\" : 0\n    },\n    \"address\": {\n        \"country\": \"Poland\",\n        \"country_code\": \"PL\",\n        \"county\": \"Wojew\u00f3dztwo dolno\u015bl\u0105skie\",\n        \"region\": \"\",\n        \"locality\": \"\",\n        \"street\": \"E67\",\n        \"house_number\": \"\",\n        \"zip\": \"55\"\n    },\n    \"inputs\":{\n        \"other\":{\n            \"virtual_gps_odometer\":0.0000,\n            \"country_code_geonames\":91\n        },\n        \"device_inputs\":{\n            \"virtual_odometer\":5.00,\n            \"digital_input_4\":false,\n            \"driver_1_state\":\"DRIVE\",\n            \"input_trigger\":0,\n            \"tco_first_driver_state\":\"DRIVE\",\n            \"priority\":\"LOW\",\n            ....,\n \n            \"hdop\":\"0.0\"\n        },\n        \"calculated_inputs\":{\n            \"din4_working_time\":0.00,\n            \"custom_input_3\":0.00,\n            \"custom_input_6\":0.00,\n            \"temperature\":0.00,\n            \"custom_input_1\":0.00,\n            ....,\n            \"custom_input_2\":0.00,\n            \"mileage\":5000.00\n    \t},\n  \t\t\"geozone_ids\": [\n          \t\"0d5d7bc2\",\n          \t\"0d5d7bc2\"\n        ],\n\t\t\"tires\": {\n            \"tire01\": {\n              \"tire_pressure_threshold_detection\": \"2\",\n              \"tire_sensor_electrical_fault\": \"2\",\n              \"tire_status\": \"1\",\n              \"tire_temperature\": \"39.5\",\n              \"tire_air_leakage_rate\": \"2001.0\",\n              \"tire_pressure\": \"400\",\n              \"tire_sensor_enable_status\": \"0\",\n              \"tire_location\": \"23\",\n              \"tire_extended_tire_pressure_support\": \"3\"\n            },\n            ....,\n            \"tire36\": {\n              \"tire_pressure_threshold_detection\": \"2\",\n              \"tire_sensor_electrical_fault\": \"2\",\n              \"tire_status\": \"1\",\n              \"tire_temperature\": \"39.5\",\n              \"tire_air_leakage_rate\": \"2036.0\",\n              \"tire_pressure\": \"400\",\n              \"tire_sensor_enable_status\": \"0\",\n              \"tire_location\": \"23\",\n              \"tire_extended_tire_pressure_support\": \"3\"\n            }\n         },\n\t.....\n}<\/pre><\/div>\n\n<p><br\/>Ako je parametar neto\u010dno unesen, sustav \u0107e odgovoriti kodom pogre\u0161ke. Svi kodovi pogre\u0161aka opisani su u odjeljku <a href=\"https:\/\/www.fmsdocumentation.com\/apis\/\">API-ji<\/a> . Parametri za koje nisu navedeni podaci nisu uklju\u010deni u odgovor. Potpuni popis parametara odgovora dostupan je na kraju ovog odjeljka.   <\/p>\n\n<h4 class=\"wp-block-heading\">Parametri odgovora:<\/h4>\n\n\n<table id=\"tablepress-167\" class=\"tablepress tablepress-id-167\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Name<\/th><th class=\"column-2\">Type<\/th><th class=\"column-3\">Array<\/th><th class=\"column-4\">Description<\/th><th class=\"column-5\">Units<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">items<\/td><td class=\"column-2\">Array<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">Contains all parameters in accordance to the request<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">object_id<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">Object identifier<\/td><td class=\"column-5\">Text<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">datetime<\/td><td class=\"column-2\">Date<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">Date and time point of coordinate generated in hardware<br \/>\nFormat: \"yyyy-mm-ddThh:mm:ss.sssZ\"<br \/>\n<\/td><td class=\"column-5\">Datetime<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">ignition_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">Indicates if the object's ignition is on<br \/>\nPossible values:<br \/>\nON <br \/>\nOFF <br \/>\nUNKNOWN <\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">trip_type<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">Trip type<br \/>\nPossible values: <br \/>\nUNKNOWN<br \/>\nNONE<br \/>\nPRIVATE<br \/>\nBUSINESS<br \/>\nWORK<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">other<\/td><td class=\"column-2\">Array<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">Container for other system parameters<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">country_code_geonames<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">other<\/td><td class=\"column-4\">Country code numeral<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">virtual_gps_odometer<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">other<\/td><td class=\"column-4\">Virtual odometer value <\/td><td class=\"column-5\">km<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">calculated_inputs<\/td><td class=\"column-2\">Array<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">Container for parameters calculated in the system from other parameters according to the configuration<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">fuel_consumption<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">Fuel consumption<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">fuel_level<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">Fuel level<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">mileage<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">Mileage<\/td><td class=\"column-5\">km<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">rpm<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">Engine RPM<\/td><td class=\"column-5\">RPM<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">Temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">custom_input_1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">Custom input 1<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">custom_input_2<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">Custom input 2<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">custom_input_3<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">Custom input 3<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">custom_input_4<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">Custom input 4<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">custom_input_5<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">Custom input 5<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">custom_input_6<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">Custom input 6<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">custom_input_7<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">Custom input 7<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">custom_input_8<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">Custom input 8<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">din1_working_time<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">DIN1 working time<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">din2_working_time<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">DIN2 working time<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">din3_working_time<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">DIN3 working time<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">din4_working_time<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">DIN4 working time<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">weight<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">calculated_inputs<\/td><td class=\"column-4\">Weight<\/td><td class=\"column-5\">kg<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">device_inputs<\/td><td class=\"column-2\">Array<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Container for parameters received from hardware<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">x_axis<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Accelerometer X axis<\/td><td class=\"column-5\">G<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">y_axis<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Accelerometer Y axis<\/td><td class=\"column-5\">G<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">z_axis<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Accelerometer Z axis<\/td><td class=\"column-5\">G<\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">g_peak_x<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">G peak in X axis<\/td><td class=\"column-5\">G<\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">g_peak_y<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">G peak in Y axis<\/td><td class=\"column-5\">G<\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">g_peak_z<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">G peak in Z axis<\/td><td class=\"column-5\">G<\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">x_axis_tilt_angle<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">X axis tilt angle<\/td><td class=\"column-5\">Degrees<\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">y_axis_tilt_angle<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Y axis tilt angle<\/td><td class=\"column-5\">Degrees<\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">z_axis_tilt_angle<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Z axis tilt angle<\/td><td class=\"column-5\">Degrees<\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">canbus_distance<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN high resolution total vehicle distance <\/td><td class=\"column-5\">km<\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\">canbus_engine_coolant_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN engine coolant temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">canbus_fuel_rate<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN fuel rate<\/td><td class=\"column-5\">l\/h<\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\">engine_rpm<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN engine speed<\/td><td class=\"column-5\">RPM<\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\">engine_hours<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN engine hours<\/td><td class=\"column-5\">h<\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">service_dist<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN service distance<\/td><td class=\"column-5\">km<\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">pedal_pos<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN accelerator pedal position<\/td><td class=\"column-5\">%<\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\">fuel_level_can<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN fuel level<\/td><td class=\"column-5\">%<\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\">fuel_used<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN engine total fuel used<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">speed_wheel<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN wheel based speed<\/td><td class=\"column-5\">km\/h<\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">speed_tacho<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN tachograph vehicle speed<\/td><td class=\"column-5\">km\/h<\/td>\n<\/tr>\n<tr class=\"row-50\">\n\t<td class=\"column-1\">tacho_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN tachograph performance<br \/>\nPossible values:<br \/>\nNORMAL_PERFORMANCE<br \/>\nPERFORMANCE_ANALYSIS<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-51\">\n\t<td class=\"column-1\">overspeeding_events<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN tacho vehicle overspeed<br \/>\nPossible values:<br \/>\nNO_OVERSPEED<br \/>\nOVERSPEED<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-52\">\n\t<td class=\"column-1\">axle_count<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN axle location<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-53\">\n\t<td class=\"column-1\">canbus_brake_switch<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN brake switch<br \/>\nPossible values:<br \/>\nRELEASED<br \/>\nPRESSED<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-54\">\n\t<td class=\"column-1\">canbus_clutch_switch<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN clutch switch<br \/>\nPossible values:<br \/>\nRELEASED<br \/>\nPRESSED<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-55\">\n\t<td class=\"column-1\">canbus_pto_state<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN PTO state<br \/>\nPossible values:<br \/>\nOFF_DISABLED<br \/>\nSET<br \/>\nNOT_AVAILABLE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-56\">\n\t<td class=\"column-1\">canbus_cruise_control_state<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN cruise control active<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-57\">\n\t<td class=\"column-1\">canbus_request_supported<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN request supported<br \/>\nPossible values:<br \/>\nNOT_SUPPORTED<br \/>\nSUPPORTED<br \/>\nRESERVED<br \/>\nDO_NOT_CARE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-58\">\n\t<td class=\"column-1\">canbus_diagnostics_supported<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN diagnostics supported<br \/>\nPossible values:<br \/>\nNOT_SUPPORTED<br \/>\nSUPPORTED<br \/>\nRESERVED<br \/>\nDO_NOT_CARE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-59\">\n\t<td class=\"column-1\">canbus_vehicle_motion<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN tacho vehicle motion<br \/>\nPossible values:<br \/>\nNOT_DETECTED<br \/>\nDETECTED<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-60\">\n\t<td class=\"column-1\">canbus_driver_1_time<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN tacho driver 1 time related status<br \/>\nPossible values:<br \/>\nNORMAL<br \/>\n15_MIN_BEFORE_4,5H<br \/>\n4,5H_REACHED<br \/>\n15_MIN_BEFORE_9H<br \/>\n9H_REACHED<br \/>\n15_MIN_BEFORE_16H<br \/>\n16H_REACHED<br \/>\nERROR<br \/>\nNOT_AVAILABLE<br \/>\n<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-61\">\n\t<td class=\"column-1\">canbus_driver_1_card<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN tacho driver 1 card<br \/>\nPossible values:<br \/>\nCARD_NOT_PRESENT<br \/>\nCARD_PRESENT<br \/>\nERROR<br \/>\nNOT_AVAILABLE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-62\">\n\t<td class=\"column-1\">canbus_driver_2_time<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN tacho driver 2 time related status<br \/>\nPossible values:<br \/>\nNORMAL<br \/>\n15_MIN_BEFORE_4,5H<br \/>\n4,5H_REACHED<br \/>\n15_MIN_BEFORE_9H<br \/>\n9H_REACHED<br \/>\n15_MIN_BEFORE_16H<br \/>\n16H_REACHED<br \/>\nERROR<br \/>\nNOT_AVAILABLE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-63\">\n\t<td class=\"column-1\">canbus_driver_2_card<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN tacho driver 2 card<br \/>\nPossible values:<br \/>\nCARD_NOT_PRESENT<br \/>\nCARD_PRESENT<br \/>\nERROR<br \/>\nNOT_AVAILABLE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-64\">\n\t<td class=\"column-1\">canbus_engine_plcs<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN engine percent load at current speed<\/td><td class=\"column-5\">%<\/td>\n<\/tr>\n<tr class=\"row-65\">\n\t<td class=\"column-1\">canbus_tire_location<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN tire location<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-66\">\n\t<td class=\"column-1\">canbus_system_event<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN system event<br \/>\nPossible values:<br \/>\nNO_TACHO_EVENT<br \/>\nTACHO_EVENT<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-67\">\n\t<td class=\"column-1\">canbus_handling_information<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN tacho handling information<br \/>\nPossible values:<br \/>\nNO_HANDLING_INFORMATION<br \/>\nHANDLING_INFORMATION<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-68\">\n\t<td class=\"column-1\">canbus_direction_indicator<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN tacho direction indicator<br \/>\nPossible values:<br \/>\nFORWARD<br \/>\nREVERSE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-69\">\n\t<td class=\"column-1\">canbus_ambient_air_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN ambient air temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-70\">\n\t<td class=\"column-1\">canbus_fuel_economy<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN instantaneous fuel economy<\/td><td class=\"column-5\">km\/l<\/td>\n<\/tr>\n<tr class=\"row-71\">\n\t<td class=\"column-1\">canbus_pto<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN at least one PTO engaged<br \/>\nPossible values:<br \/>\nNO_PTO_DRIVER<br \/>\nAT_LEAST_ONE_PTO_DRIVER<br \/>\nERROR<br \/>\nNOT_AVAILABLE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-72\">\n\t<td class=\"column-1\">canbus_hrfc<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN high resolution engine total fuel used<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-73\">\n\t<td class=\"column-1\">vehicle_id<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN vehicle ID<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-74\">\n\t<td class=\"column-1\">first_driver_id<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN first driver ID<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-75\">\n\t<td class=\"column-1\">second_driver_id<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN second driver ID<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-76\">\n\t<td class=\"column-1\">canbus_driver_1_state<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN tacho driver 1 working state<br \/>\nPossible values:<br \/>\nREST<br \/>\nDRIVER_AVAILABLE<br \/>\nWORK<br \/>\nDRIVE<br \/>\nERROR<br \/>\nNOT_AVAILABLE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-77\">\n\t<td class=\"column-1\">canbus_driver_2_state<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN tacho driver 2 working state<br \/>\nPossible values:<br \/>\nREST<br \/>\nDRIVER_AVAILABLE<br \/>\nWORK<br \/>\nDRIVE<br \/>\nERROR<br \/>\nNOT_AVAILABLE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-78\">\n\t<td class=\"column-1\">canbus_axle_weight_1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN axle 1 weight<\/td><td class=\"column-5\">kg<\/td>\n<\/tr>\n<tr class=\"row-79\">\n\t<td class=\"column-1\">canbus_axle_weight_2<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN axle 2 weight<\/td><td class=\"column-5\">kg<\/td>\n<\/tr>\n<tr class=\"row-80\">\n\t<td class=\"column-1\">canbus_axle_weight_3<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN axle 3 weight<\/td><td class=\"column-5\">kg<\/td>\n<\/tr>\n<tr class=\"row-81\">\n\t<td class=\"column-1\">canbus_axle_weight_4<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN axle 4 weight<\/td><td class=\"column-5\">kg<\/td>\n<\/tr>\n<tr class=\"row-82\">\n\t<td class=\"column-1\">canbus_axle_weight_5<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN axle 5 weight<\/td><td class=\"column-5\">kg<\/td>\n<\/tr>\n<tr class=\"row-83\">\n\t<td class=\"column-1\">fuel_level_can_l<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN fuel level liters<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-84\">\n\t<td class=\"column-1\">fuel_used_diff<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN fuel used delta<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-85\">\n\t<td class=\"column-1\">canbus_parking_brake_switch<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN parking brake switch<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-86\">\n\t<td class=\"column-1\">canbus_battery_power<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN battery power<\/td><td class=\"column-5\">%<\/td>\n<\/tr>\n<tr class=\"row-87\">\n\t<td class=\"column-1\">canbus_distance_until_recharge<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN distance until recharge<\/td><td class=\"column-5\">km<\/td>\n<\/tr>\n<tr class=\"row-88\">\n\t<td class=\"column-1\">canbus_battery_charging<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN battery charging<br \/>\nPossible values:<br \/>\nNO_CHARGING<br \/>\nCHARGING<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-89\">\n\t<td class=\"column-1\">lcv_hood<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">LCV hood<br \/>\nPossible values:<br \/>\nCLOSE<br \/>\nOPEN<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-90\">\n\t<td class=\"column-1\">lcv_driver_doors<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">LCV driver doors<br \/>\nPossible values:<br \/>\nCLOSE<br \/>\nOPEN<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-91\">\n\t<td class=\"column-1\">lcv_passenger_doors<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">LCV passenger doors<br \/>\nPossible values:<br \/>\nCLOSE<br \/>\nOPEN<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-92\">\n\t<td class=\"column-1\">lcv_left_back_doors<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">LCV left back doors<br \/>\nPossible values:<br \/>\nCLOSE<br \/>\nOPEN<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-93\">\n\t<td class=\"column-1\">lcv_right_back_doors<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">LCV right back doors<br \/>\nPossible values:<br \/>\nCLOSE<br \/>\nOPEN<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-94\">\n\t<td class=\"column-1\">lcv_trunk<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">LCV trunk<br \/>\nPossible values:<br \/>\nCLOSE<br \/>\nOPEN<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-95\">\n\t<td class=\"column-1\">canbus_hours_to_service<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN hours to service<\/td><td class=\"column-5\">h<\/td>\n<\/tr>\n<tr class=\"row-96\">\n\t<td class=\"column-1\">can_interface_configuration_can1_interface<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN interface configuration CAN1 interface<br \/>\nPossible values:<br \/>\nNONE<br \/>\nFMS<br \/>\nLCV<br \/>\nOBD<br \/>\nTACHO<br \/>\nMOBILEYE<br \/>\nTRAILERS<br \/>\nDXP<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-97\">\n\t<td class=\"column-1\">can_interface_configuration_can2_interface<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN interface configuration CAN2 interface<br \/>\nPossible values:<br \/>\nNONE<br \/>\nFMS<br \/>\nLCV<br \/>\nOBD<br \/>\nTACHO<br \/>\nMOBILEYE<br \/>\nTRAILERS<br \/>\nDXP<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-98\">\n\t<td class=\"column-1\">can_interface_configuration_can1_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN interface configuration CAN1 status<br \/>\nPossible values:<br \/>\nINACTIVE<br \/>\nACTIVE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-99\">\n\t<td class=\"column-1\">can_interface_configuration_can1_mode<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN interface configuration CAN1 mode<br \/>\nPossible values:<br \/>\nSILENT<br \/>\nACTIVE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-100\">\n\t<td class=\"column-1\">can_interface_configuration_can1_auto_baud_rate<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN interface configuration CAN1 auto baud rate<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-101\">\n\t<td class=\"column-1\">can_interface_configuration_can1_ff_filters_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN interface configuration CAN1 filters status<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-102\">\n\t<td class=\"column-1\">can_interface_configuration_can2_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN interface configuration CAN2 status<br \/>\nPossible values:<br \/>\nINACTIVE<br \/>\nACTIVE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-103\">\n\t<td class=\"column-1\">can_interface_configuration_can2_mode<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN interface configuration CAN2 mode<br \/>\nPossible values:<br \/>\nSILENT<br \/>\nACTIVE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-104\">\n\t<td class=\"column-1\">can_interface_configuration_can2_auto_baud_rate<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN interface configuration CAN2 auto baud rate<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-105\">\n\t<td class=\"column-1\">can_interface_configuration_can2_ff_filters_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN interface configuration CAN2 filters status<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-106\">\n\t<td class=\"column-1\">canbus_electric_motor_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN electric motor temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-107\">\n\t<td class=\"column-1\">can_lcv_configuration_can2_subgroup<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN LCV configuration CAN2 subgroup<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-108\">\n\t<td class=\"column-1\">can_lcv_configuration_can1_subgroup<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN LCV configuration CAN1 subgroup<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-109\">\n\t<td class=\"column-1\">can_lcv_configuration_can2_group<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN LCV configuration CAN2 group<br \/>\nPossible values:<br \/>\nVAG<br \/>\nMERCEDES<br \/>\nCITROEN<br \/>\nFORD<br \/>\nFIAT<br \/>\nOPEL<br \/>\nRENAULT<br \/>\nTOYOTA<br \/>\nTRACTOR<br \/>\nTRUCK<br \/>\nHYUNDAI<br \/>\nLEXUS<br \/>\nVOLVO<br \/>\nBMW<br \/>\nNISSAN<br \/>\nHONDA<br \/>\nMITSUBISHI<br \/>\nSUBARU<br \/>\nCHRYSLER<br \/>\nISUZU<br \/>\nSSANGYONG<br \/>\nMAZDA<br \/>\nKOMATSU<br \/>\nRANGEROVER<br \/>\nCLAAS<br \/>\nSAAB<br \/>\nLANDROVER<br \/>\nPORSCHE<br \/>\nKIA<br \/>\nJAGUAR<br \/>\nINFINITI<br \/>\nLINDE<br \/>\nHITACHI<br \/>\nSUZUKI<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-110\">\n\t<td class=\"column-1\">can_lcv_configuration_can1_group<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN LCV configuration CAN1 group<br \/>\nPossible values:<br \/>\nVAG<br \/>\nMERCEDES<br \/>\nCITROEN<br \/>\nFORD<br \/>\nFIAT<br \/>\nOPEL<br \/>\nRENAULT<br \/>\nTOYOTA<br \/>\nTRACTOR<br \/>\nTRUCK<br \/>\nHYUNDAI<br \/>\nLEXUS<br \/>\nVOLVO<br \/>\nBMW<br \/>\nNISSAN<br \/>\nHONDA<br \/>\nMITSUBISHI<br \/>\nSUBARU<br \/>\nCHRYSLER<br \/>\nISUZU<br \/>\nSSANGYONG<br \/>\nMAZDA<br \/>\nKOMATSU<br \/>\nRANGEROVER<br \/>\nCLAAS<br \/>\nSAAB<br \/>\nLANDROVER<br \/>\nPORSCHE<br \/>\nKIA<br \/>\nJAGUAR<br \/>\nINFINITI<br \/>\nLINDE<br \/>\nHITACHI<br \/>\nSUZUKI<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-111\">\n\t<td class=\"column-1\">can_ignition<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN ignition<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-112\">\n\t<td class=\"column-1\">can_lcv_window_state_front_left<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN LCV window state Front Left<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-113\">\n\t<td class=\"column-1\">can_lcv_window_state_front_right<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN LCV window state Front Right<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-114\">\n\t<td class=\"column-1\">can_lcv_window_state_back_left<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN LCV window state Back Left<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-115\">\n\t<td class=\"column-1\">can_lcv_window_state_back_right<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN LCV window state Back Right<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-116\">\n\t<td class=\"column-1\">can_lcv_window_state_sunroof<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN LCV window state Sunroof<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-117\">\n\t<td class=\"column-1\">can_fuel_level_milliliters<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN fuel level millliliters<\/td><td class=\"column-5\">ml<\/td>\n<\/tr>\n<tr class=\"row-118\">\n\t<td class=\"column-1\">can_door_lock_state<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">CAN door lock state<br \/>\nPossible values:<br \/>\nUNLOCKED<br \/>\nLOCKED<br \/>\nNOT_AVAILABLE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-119\">\n\t<td class=\"column-1\">gsm_signal_strength<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">GSM signal strength<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-120\">\n\t<td class=\"column-1\">operator<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">GSM operator<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-121\">\n\t<td class=\"column-1\">gps_speed<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">GPS speed<\/td><td class=\"column-5\">km\/h<\/td>\n<\/tr>\n<tr class=\"row-122\">\n\t<td class=\"column-1\">gsm_umts_signal_strength<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">GSM\/UMTS signal strength<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-123\">\n\t<td class=\"column-1\">gsm_umts_operator<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">GSM\/UMTS operator<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-124\">\n\t<td class=\"column-1\">umts_enabled<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">UMTS enabled status<br \/>\nPossible values:<br \/>\nDISABLED<br \/>\nENABLED<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-125\">\n\t<td class=\"column-1\">gnss_antenna<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">GNSS antenna status<br \/>\nPossible values:<br \/>\nDISABLED<br \/>\nENABLED<br \/>\nUNKNOWN<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-126\">\n\t<td class=\"column-1\">gsm_umts_jamming<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">GSM\/UMTS jamming status<br \/>\nPossible status:<br \/>\nJAMMING_NOT_DETECTED<br \/>\nJAMMING_DETECTED<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-127\">\n\t<td class=\"column-1\">gprs_errors<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">GPRS errors<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-128\">\n\t<td class=\"column-1\">gprs_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">GPRS status<br \/>\nPossible values:<br \/>\nDISCONNECTED<br \/>\nCONNECTED<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-129\">\n\t<td class=\"column-1\">gps_altitude<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">GPS altitude<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-130\">\n\t<td class=\"column-1\">dout1_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DOUT1 status<br \/>\nPossible values:<br \/>\nACTIVE<br \/>\nINACTIVE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-131\">\n\t<td class=\"column-1\">dout2_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DOUT2 status<br \/>\nPossible values:<br \/>\nACTIVE<br \/>\nINACTIVE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-132\">\n\t<td class=\"column-1\">dxp_battery_battery_voltage<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP battery voltage<\/td><td class=\"column-5\">V<\/td>\n<\/tr>\n<tr class=\"row-133\">\n\t<td class=\"column-1\">dxp_battery_nominal_capacity_used<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP battery nominal capacity used<\/td><td class=\"column-5\">A<\/td>\n<\/tr>\n<tr class=\"row-134\">\n\t<td class=\"column-1\">dxp_battery_charging_counter<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP battery charging counter<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-135\">\n\t<td class=\"column-1\">dxp_battery_state_of_charge<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP battery charging state<\/td><td class=\"column-5\">%<\/td>\n<\/tr>\n<tr class=\"row-136\">\n\t<td class=\"column-1\">dxp_battery_charging_current<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP battery charging current<\/td><td class=\"column-5\">A<\/td>\n<\/tr>\n<tr class=\"row-137\">\n\t<td class=\"column-1\">dxp_battery_battery_current<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP battery current<\/td><td class=\"column-5\">A<\/td>\n<\/tr>\n<tr class=\"row-138\">\n\t<td class=\"column-1\">dxp_battery_battery_temp<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP battery temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-139\">\n\t<td class=\"column-1\">dxp_battery_charger_stop_reason<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP battery charge stop reason<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-140\">\n\t<td class=\"column-1\">dxp_switches_switch1<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP switch 1 value<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-141\">\n\t<td class=\"column-1\">dxp_switches_switch2<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP switch 2 value<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-142\">\n\t<td class=\"column-1\">dxp_switches_switch3<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP switch 3 value<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-143\">\n\t<td class=\"column-1\">dxp_switches_switch4<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP switch 4 value<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-144\">\n\t<td class=\"column-1\">dxp_switches_switch5<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP switch 5 value<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-145\">\n\t<td class=\"column-1\">dxp_switches_switch6<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP switch 6 value<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-146\">\n\t<td class=\"column-1\">dxp_switches_switch7<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP switch 7 value<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-147\">\n\t<td class=\"column-1\">dxp_switches_switch8<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP switch 8 value<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-148\">\n\t<td class=\"column-1\">dxp_switches_parameters_set<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP switch parameters set<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-149\">\n\t<td class=\"column-1\">dxp_other_parameters_chassis_number_nr<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP chassis number<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-150\">\n\t<td class=\"column-1\">dxp_other_parameters_servie_odometer<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP service odometer<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-151\">\n\t<td class=\"column-1\">dxp_other_parameters_vcl_version<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP VCL version<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-152\">\n\t<td class=\"column-1\">dxp_other_parameters_parameter_blk_version<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP parameter BLK version<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-153\">\n\t<td class=\"column-1\">dxp_faults1_status1_faults_error_codes<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP status 1 fault error codes<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-154\">\n\t<td class=\"column-1\">dxp_faults1_status2_faults_error_codes<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP status 2 fault error codes<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-155\">\n\t<td class=\"column-1\">dxp_faults1_status3_faults_error_codes<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP status 3 fault error codes<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-156\">\n\t<td class=\"column-1\">dxp_faults1_status4_faults_error_codes<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP status 4 fault error codes<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-157\">\n\t<td class=\"column-1\">dxp_faults1_status5_faults_error_codes<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP status 5 fault error codes<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-158\">\n\t<td class=\"column-1\">dxp_faults1_status6_faults_error_codes<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP status 6 fault error codes<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-159\">\n\t<td class=\"column-1\">dxp_faults1_status7_faults_error_codes<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP status 7 fault error codes<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-160\">\n\t<td class=\"column-1\">dxp_faults1_status8_faults_error_codes<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP status 8 fault error codes<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-161\">\n\t<td class=\"column-1\">dxp_faults2_user_fault_1_error_codes<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP user fault 1 error codes<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-162\">\n\t<td class=\"column-1\">dxp_faults2_user_fault_2_error_codes<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP user fault 2 error codes<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-163\">\n\t<td class=\"column-1\">dxp_faults2_user_fault_2_history_error_codes<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP user fault 1 history error codes<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-164\">\n\t<td class=\"column-1\">dxp_faults2_user_fault_1_history_error_codes<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP user fault 2 history error codes<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-165\">\n\t<td class=\"column-1\">dxp_faults2_kyb_hist_fault_codes<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP KYB hist fault codes<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-166\">\n\t<td class=\"column-1\">dxp_charger_status<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DXP charger status<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-167\">\n\t<td class=\"column-1\">ecodrive_maximum_speed<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive maximum speed<\/td><td class=\"column-5\">km\/h<\/td>\n<\/tr>\n<tr class=\"row-168\">\n\t<td class=\"column-1\">ecodrive_overspeed<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive overspeeding timer<\/td><td class=\"column-5\">s<\/td>\n<\/tr>\n<tr class=\"row-169\">\n\t<td class=\"column-1\">ecodrive_rpm_on_red<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive RPM in red band timer<\/td><td class=\"column-5\">s<\/td>\n<\/tr>\n<tr class=\"row-170\">\n\t<td class=\"column-1\">ecodrive_maximum_rpm<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive maximum RPM<\/td><td class=\"column-5\">RPM<\/td>\n<\/tr>\n<tr class=\"row-171\">\n\t<td class=\"column-1\">ecodrive_braking_events<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive brake counter<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-172\">\n\t<td class=\"column-1\">ecodrive_harsh_acceleration<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive harsh acceleration counter<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-173\">\n\t<td class=\"column-1\">ecodrive_idling_time<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive idling counter<\/td><td class=\"column-5\">s<\/td>\n<\/tr>\n<tr class=\"row-174\">\n\t<td class=\"column-1\">ecodrive_engine_on<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive engine on timer<\/td><td class=\"column-5\">s<\/td>\n<\/tr>\n<tr class=\"row-175\">\n\t<td class=\"column-1\">ecodrive_time_cruise_control_could_be_on<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive time cruise control could be on<\/td><td class=\"column-5\">s<\/td>\n<\/tr>\n<tr class=\"row-176\">\n\t<td class=\"column-1\">ecodrive_time_cruise_control_was_on_when_it_could_be_on<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive time cruise control was on when it could be on<\/td><td class=\"column-5\">s<\/td>\n<\/tr>\n<tr class=\"row-177\">\n\t<td class=\"column-1\">ecodrive_extreme_braking_count<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive extreme braking count<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-178\">\n\t<td class=\"column-1\">ecodrive_harsh_braking_count<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive harsh braking count<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-179\">\n\t<td class=\"column-1\">ecodrive_mileage_in_rpm_green_zone<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive mileage in RPM green zone<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-180\">\n\t<td class=\"column-1\">ecodrive_mileage_when_speed_is_below_overspeed<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive mileage when speed is below overspeed<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-181\">\n\t<td class=\"column-1\">ecodrive_mileage_when_cruise_control_could_be_on<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive mileage when cruise control could be on<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-182\">\n\t<td class=\"column-1\">ecodrive_mileage_when_cruise_control_was_on_when_it_could_be_on<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive mileage when cruise control was on when it could be on<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-183\">\n\t<td class=\"column-1\">ecodrive_cornering_counter<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive cornering counter<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-184\">\n\t<td class=\"column-1\">ecodrive_stops_counter<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive stop counter<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-185\">\n\t<td class=\"column-1\">ecodrive_fuel_used_at_stops<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive fuel used while idling<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-186\">\n\t<td class=\"column-1\">ecodrive_mileage_while_free_rolling<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive free rolling distance<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-187\">\n\t<td class=\"column-1\">ecodrive_mileage_while_engine_overloaded<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive engine overloaded distance<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-188\">\n\t<td class=\"column-1\">ecodrive_fuel_used_while_engine_overloaded<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive engine overloaded fuel used<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-189\">\n\t<td class=\"column-1\">ecodrive_mileage_while_overspeeding<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive overspeeding distance<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-190\">\n\t<td class=\"column-1\">ecodrive_fuel_used_while_overspeeding<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive overspeeding fuel used<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-191\">\n\t<td class=\"column-1\">ecodrive_mileage_when_cruise_control_was_on<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive cruise control on distance<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-192\">\n\t<td class=\"column-1\">ecodrive_fuel_used_when_when_cruise_control_was_on<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive cruise control on fuel used<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-193\">\n\t<td class=\"column-1\">ecodrive_mileage_in_highest_gear<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive highest gear distance<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-194\">\n\t<td class=\"column-1\">ecodrive_fuel_used_in_highest_gear<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive highest gear fuel used<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-195\">\n\t<td class=\"column-1\">ecodrive_mileage_in_range_1_900_rpm<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive RPM range 1 (<900 RPM) distance<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-196\">\n\t<td class=\"column-1\">ecodrive_fuel_used_in_range_1_900_rpm<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive RPM range 1 (<900 RPM) fuel used<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-197\">\n\t<td class=\"column-1\">ecodrive_mileage_in_range_900_1300_rpm<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive RPM range 2 (900-1300 RPM) distance<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-198\">\n\t<td class=\"column-1\">ecodrive_fuel_used_in_range_900_1300_rpm<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive RPM range 2 (900-1300 RPM) fuel used<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-199\">\n\t<td class=\"column-1\">ecodrive_mileage_in_range_1300_1500_rpm<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive RPM range 3 (1300-1500 RPM) distance<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-200\">\n\t<td class=\"column-1\">ecodrive_fuel_used_in_range_1300_1500_rpm<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive RPM range 3 (1300-1500 RPM) fuel used<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-201\">\n\t<td class=\"column-1\">ecodrive_mileage_in_range_1500_2300_rpm<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive RPM range 4 (1500-2300 RPM) distance<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-202\">\n\t<td class=\"column-1\">ecodrive_fuel_used_in_range_1500_2300_rpm<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive RPM range 4 (1500-2300 RPM) fuel used<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-203\">\n\t<td class=\"column-1\">ecodrive_idling_state<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive idling state<br \/>\nPossible values:<br \/>\nNO_IDLING<br \/>\nIDLING<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-204\">\n\t<td class=\"column-1\">ecodrive_braking_value<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive braking value<\/td><td class=\"column-5\">m\/s^2<\/td>\n<\/tr>\n<tr class=\"row-205\">\n\t<td class=\"column-1\">ecodrive_acceleration_value<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive acceleration value<\/td><td class=\"column-5\">m\/s^2<\/td>\n<\/tr>\n<tr class=\"row-206\">\n\t<td class=\"column-1\">ecodrive_cornering_value<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive cornering value <\/td><td class=\"column-5\">m\/s^2<\/td>\n<\/tr>\n<tr class=\"row-207\">\n\t<td class=\"column-1\">eco_rpm_in_red_band_distance<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive RPM in red band distance<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-208\">\n\t<td class=\"column-1\">eco_engine_braking_distance<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive engine braking distance<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-209\">\n\t<td class=\"column-1\">eco_braking_distance<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive braking distance<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-210\">\n\t<td class=\"column-1\">eco_braking_duration<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive braking duration<\/td><td class=\"column-5\">s<\/td>\n<\/tr>\n<tr class=\"row-211\">\n\t<td class=\"column-1\">eco_retarder_duration<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive retarder duration<\/td><td class=\"column-5\">s<\/td>\n<\/tr>\n<tr class=\"row-212\">\n\t<td class=\"column-1\">eco_stops_counter<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Eco-Drive stop counter<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-213\">\n\t<td class=\"column-1\">thermoking_air_return_temp<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing air return temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-214\">\n\t<td class=\"column-1\">thermoking_alarms<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing alarm code<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-215\">\n\t<td class=\"column-1\">thermoking_set_point<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing temperature setpoint<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-216\">\n\t<td class=\"column-1\">thermoking_fuel_level<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing fuel level<\/td><td class=\"column-5\">%<\/td>\n<\/tr>\n<tr class=\"row-217\">\n\t<td class=\"column-1\">thermoking_battery_voltage<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing battery voltage<\/td><td class=\"column-5\">V<\/td>\n<\/tr>\n<tr class=\"row-218\">\n\t<td class=\"column-1\">thermoking_total_electric_hours<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing total electric hours<\/td><td class=\"column-5\">h<\/td>\n<\/tr>\n<tr class=\"row-219\">\n\t<td class=\"column-1\">thermoking_vehicle_hours<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing total vehicle hours<\/td><td class=\"column-5\">h<\/td>\n<\/tr>\n<tr class=\"row-220\">\n\t<td class=\"column-1\">thermoking_total_engine_hours<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing total engine hours<\/td><td class=\"column-5\">h<\/td>\n<\/tr>\n<tr class=\"row-221\">\n\t<td class=\"column-1\">thermoking_alarm_type<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing alarm type<br \/>\nPossible values:<br \/>\nNO_ALARM<br \/>\nLOG_STORED_OR_ROUTINE_MAINTENANCE<br \/>\nLOW_FUEL<br \/>\nMAINTENANCE_PAST_DUE<br \/>\nRESERVED<br \/>\nIMMEDIATE_ATTENTION_REQUIRED<br \/>\nSHUTDOWN_OR_CATASTROPHIC_SYSTEM_FAILURE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-222\">\n\t<td class=\"column-1\">thermoking_discharge_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing discharge air temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-223\">\n\t<td class=\"column-1\">thermoking_evaporator_coil_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing evaporator coil temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-224\">\n\t<td class=\"column-1\">thermoking_operating_mode<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing operating mode<br \/>\nPossible values:<br \/>\nPOWER_OFF_OR_UNKNOWN<br \/>\nCOOLING<br \/>\nHEATING<br \/>\nDEFROST<br \/>\nNULL<br \/>\nPRETRIP<br \/>\nSLEEP<br \/>\nRESERVED<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-225\">\n\t<td class=\"column-1\">thermoking_cycle_mode<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing cycle mode<br \/>\nPossible values:<br \/>\nCYCLE_SENTRY_MODE<br \/>\nCONTINUOUS_MODE<br \/>\nSTART_STOP_MODE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-226\">\n\t<td class=\"column-1\">thermoking_high_speed_status<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing high speed status<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-227\">\n\t<td class=\"column-1\">thermoking_door_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing door status<br \/>\nPossible values:<br \/>\nCLOSED<br \/>\nOPEN<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-228\">\n\t<td class=\"column-1\">thermoking_diesel_electric_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">ThermoKing diesel\/electric status<br \/>\nPossible values:<br \/>\nDIESEL_MODE<br \/>\nELECTRIC_MODE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-229\">\n\t<td class=\"column-1\">tk_touchprint_input_1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TK Touchprint input 1<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-230\">\n\t<td class=\"column-1\">tk_touchprint_input_2<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TK Touchprint input 2<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-231\">\n\t<td class=\"column-1\">tk_touchprint_input_3<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TK Touchprint input 3<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-232\">\n\t<td class=\"column-1\">tk_touchprint_input_4<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TK Touchprint input 4<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-233\">\n\t<td class=\"column-1\">tk_touchprint_input_5<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TK Touchprint input 5<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-234\">\n\t<td class=\"column-1\">tk_touchprint_input_6<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TK Touchprint input 6<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-235\">\n\t<td class=\"column-1\">tk_temperature_sensor1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TK temperature sensor 1<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-236\">\n\t<td class=\"column-1\">tk_temperature_sensor2<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TK temperature sensor 2<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-237\">\n\t<td class=\"column-1\">tk_temperature_sensor3<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TK temperature sensor 3<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-238\">\n\t<td class=\"column-1\">tk_temperature_sensor4<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TK temperature sensor 4<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-239\">\n\t<td class=\"column-1\">tk_temperature_sensor5<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TK temperature sensor 5<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-240\">\n\t<td class=\"column-1\">tk_temperature_sensor6<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TK temperature sensor 6<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-241\">\n\t<td class=\"column-1\">fuel_counter<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Fuel counter 1 <\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-242\">\n\t<td class=\"column-1\">digital_fuel_sensor_a1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor A1<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-243\">\n\t<td class=\"column-1\">fuel_counter_2<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Fuel counter 2<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-244\">\n\t<td class=\"column-1\">digital_fuel_sensor_b1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor B1<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-245\">\n\t<td class=\"column-1\">digital_fuel_sensor_a2<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor A2<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-246\">\n\t<td class=\"column-1\">digital_fuel_sensor_a3<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor A3<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-247\">\n\t<td class=\"column-1\">digital_fuel_sensor_a4<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor A4<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-248\">\n\t<td class=\"column-1\">digital_fuel_sensor_a5<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor A5<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-249\">\n\t<td class=\"column-1\">digital_fuel_sensor_a6<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor A6<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-250\">\n\t<td class=\"column-1\">digital_fuel_sensor_a7<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor A7<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-251\">\n\t<td class=\"column-1\">digital_fuel_sensor_a8<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor A8<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-252\">\n\t<td class=\"column-1\">digital_fuel_sensor_a9<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor A9<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-253\">\n\t<td class=\"column-1\">digital_fuel_sensor_a10<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor A10<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-254\">\n\t<td class=\"column-1\">digital_fuel_sensorc1_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C1 temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-255\">\n\t<td class=\"column-1\">digital_fuel_sensorc2_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C2 temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-256\">\n\t<td class=\"column-1\">digital_fuel_sensorc3_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C3 temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-257\">\n\t<td class=\"column-1\">digital_fuel_sensorc4_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C4 temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-258\">\n\t<td class=\"column-1\">digital_fuel_sensorc5_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C5 temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-259\">\n\t<td class=\"column-1\">digital_fuel_sensorc6_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C6 temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-260\">\n\t<td class=\"column-1\">digital_fuel_sensorc7_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C7 temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-261\">\n\t<td class=\"column-1\">digital_fuel_sensorc8_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C8 temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-262\">\n\t<td class=\"column-1\">digital_fuel_sensorc9_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C9 temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-263\">\n\t<td class=\"column-1\">digital_fuel_sensorc10_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C10 temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-264\">\n\t<td class=\"column-1\">digital_fuel_sensorc1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C1<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-265\">\n\t<td class=\"column-1\">digital_fuel_sensorc2<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C2<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-266\">\n\t<td class=\"column-1\">digital_fuel_sensorc3<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C3<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-267\">\n\t<td class=\"column-1\">digital_fuel_sensorc4<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C4<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-268\">\n\t<td class=\"column-1\">digital_fuel_sensorc5<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C5<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-269\">\n\t<td class=\"column-1\">digital_fuel_sensorc6<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C6<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-270\">\n\t<td class=\"column-1\">digital_fuel_sensorc7<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C7<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-271\">\n\t<td class=\"column-1\">digital_fuel_sensorc8<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C8<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-272\">\n\t<td class=\"column-1\">digital_fuel_sensorc9<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C9<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-273\">\n\t<td class=\"column-1\">digital_fuel_sensorc10<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor C10<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-274\">\n\t<td class=\"column-1\">digital_fuel_sensora1_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Digital fuel sensor A1 temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-275\">\n\t<td class=\"column-1\">fuel_level_sensorb1_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Fuel level sensor B1 temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-276\">\n\t<td class=\"column-1\">bt_humidity_sensor_0<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">BT humidity sensor 0<\/td><td class=\"column-5\">%<\/td>\n<\/tr>\n<tr class=\"row-277\">\n\t<td class=\"column-1\">bt_humidity_sensor_1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">BT humidity sensor 1<\/td><td class=\"column-5\">%<\/td>\n<\/tr>\n<tr class=\"row-278\">\n\t<td class=\"column-1\">bt_humidity_sensor_2<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">BT humidity sensor 2<\/td><td class=\"column-5\">%<\/td>\n<\/tr>\n<tr class=\"row-279\">\n\t<td class=\"column-1\">bt_humidity_sensor_3<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">BT humidity sensor 3<\/td><td class=\"column-5\">%<\/td>\n<\/tr>\n<tr class=\"row-280\">\n\t<td class=\"column-1\">bt_humidity_sensor_4<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">BT humidity sensor 4<\/td><td class=\"column-5\">%<\/td>\n<\/tr>\n<tr class=\"row-281\">\n\t<td class=\"column-1\">ibutton<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">iButton driver ID<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-282\">\n\t<td class=\"column-1\">rfid_a<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">RFID PortA<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-283\">\n\t<td class=\"column-1\">rfid_b<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">RFID PortB<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-284\">\n\t<td class=\"column-1\">magnetic_card_id<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Magnetic card ID<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-285\">\n\t<td class=\"column-1\">ds1971_ibutton_internal_8b_driver_id<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DS1971 iButton internal 8B driver ID<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-286\">\n\t<td class=\"column-1\">ds1971_ibutton_internal_16b_driver_id<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DS1971 iButton internal 16B driver ID<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-287\">\n\t<td class=\"column-1\">ds1971_ibutton_internal_8b_passenger_id<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DS1971 iButton internal 8B passenger ID<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-288\">\n\t<td class=\"column-1\">ds1971_ibutton_internal_16b_passenger_id<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DS1971 iButton internal 16B passenger ID<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-289\">\n\t<td class=\"column-1\">ultra_high_frequency_rfid_port_b<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Ultra High Frequency RFID port B<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-290\">\n\t<td class=\"column-1\">ultra_high_frequency_rfid_port_a<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Ultra High Frequency RFID port A<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-291\">\n\t<td class=\"column-1\">digital_input_1<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DIN1 value<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-292\">\n\t<td class=\"column-1\">digital_input_2<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DIN2 value<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-293\">\n\t<td class=\"column-1\">digital_input_3<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DIN3 value<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-294\">\n\t<td class=\"column-1\">digital_input_4<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DIN4 value<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-295\">\n\t<td class=\"column-1\">analog_input_1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">AIN1 value<\/td><td class=\"column-5\">V<\/td>\n<\/tr>\n<tr class=\"row-296\">\n\t<td class=\"column-1\">analog_input_2<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">AIN2 value<\/td><td class=\"column-5\">V<\/td>\n<\/tr>\n<tr class=\"row-297\">\n\t<td class=\"column-1\">din1_working_time_diff<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DIN1 hour counter<\/td><td class=\"column-5\">s<\/td>\n<\/tr>\n<tr class=\"row-298\">\n\t<td class=\"column-1\">din2_working_time_diff<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DIN2 hour counter<\/td><td class=\"column-5\">s<\/td>\n<\/tr>\n<tr class=\"row-299\">\n\t<td class=\"column-1\">din3_working_time_diff<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DIN3 hour counter<\/td><td class=\"column-5\">s<\/td>\n<\/tr>\n<tr class=\"row-300\">\n\t<td class=\"column-1\">din4_working_time_diff<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">DIN4 hour counter<\/td><td class=\"column-5\">s<\/td>\n<\/tr>\n<tr class=\"row-301\">\n\t<td class=\"column-1\">ot_digital_input_1<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OT digital input 1<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-302\">\n\t<td class=\"column-1\">ot_digital_input_2<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OT digital input 2<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-303\">\n\t<td class=\"column-1\">ot_digital_input_3<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OT digital input 3<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-304\">\n\t<td class=\"column-1\">ot_digital_input_4<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OT digital input 4<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-305\">\n\t<td class=\"column-1\">frequency_input_1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Frequency input 1<\/td><td class=\"column-5\">Hz<\/td>\n<\/tr>\n<tr class=\"row-306\">\n\t<td class=\"column-1\">frequency_input_2<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Frequency input 2<\/td><td class=\"column-5\">Hz<\/td>\n<\/tr>\n<tr class=\"row-307\">\n\t<td class=\"column-1\">kimax_total_trailer_weight<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Kimax total trailer weight<\/td><td class=\"column-5\">kg<\/td>\n<\/tr>\n<tr class=\"row-308\">\n\t<td class=\"column-1\">kimax_total_truck_weight<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Kimax total truck weight<\/td><td class=\"column-5\">kg<\/td>\n<\/tr>\n<tr class=\"row-309\">\n\t<td class=\"column-1\">moba_netto_weight<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">MOBA netto weight<\/td><td class=\"column-5\">g<\/td>\n<\/tr>\n<tr class=\"row-310\">\n\t<td class=\"column-1\">moba_timestamp<\/td><td class=\"column-2\">Datetime<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">MOBA timestamp<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-311\">\n\t<td class=\"column-1\">moba_rfid_id<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">MOBA RFID ID<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-312\">\n\t<td class=\"column-1\">mobileye_sound_type<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye sound type<br \/>\nPossible values:<br \/>\nSILENT<br \/>\nLDWL<br \/>\nLDWR<br \/>\nHW1<br \/>\nTSR<br \/>\nUFCW<br \/>\nFCW_PCW<br \/>\nPEDS_IN_DZ<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-313\">\n\t<td class=\"column-1\">mobileye_pedestrians_in_dz<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye pedestrians in danger zone<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-314\">\n\t<td class=\"column-1\">mobileye_pedestrians_fcw<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye pedestrians forward collision warning<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-315\">\n\t<td class=\"column-1\">mobileye_night_time_indicator<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye night time indicator<br \/>\nPossible values:<br \/>\nDAY<br \/>\nNIGHT<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-316\">\n\t<td class=\"column-1\">mobileye_dusk_time_indicator<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye dusk time indicator<br \/>\nPossible values:<br \/>\nDAY<br \/>\nDUSK<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-317\">\n\t<td class=\"column-1\">mobileye_error_code<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye error code<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-318\">\n\t<td class=\"column-1\">mobileye_error_valid<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye error valid<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-319\">\n\t<td class=\"column-1\">mobileye_zero_speed<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye zero speed<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-320\">\n\t<td class=\"column-1\">mobileye_headway_valid<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye headway valid<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-321\">\n\t<td class=\"column-1\">mobileye_headway_measurement<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye headway measurement<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-322\">\n\t<td class=\"column-1\">mobileye_ldw_off<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye LDW off<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-323\">\n\t<td class=\"column-1\">mobileye_right_ldw_on<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye right LDW on<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-324\">\n\t<td class=\"column-1\">mobileye_left_ldw_on<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye left LDW on<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-325\">\n\t<td class=\"column-1\">mobileye_maintenance<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye maintenance<br \/>\nPossible values:<br \/>\nNO_ERROR<br \/>\nERROR<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-326\">\n\t<td class=\"column-1\">mobileye_failsafe<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye failsafe<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-327\">\n\t<td class=\"column-1\">mobileye_fcw_on<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye forward collision warning on<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-328\">\n\t<td class=\"column-1\">mobileye_headway_warning_level<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye headway warning level<br \/>\nPossible values:<br \/>\nNO_COPV<br \/>\nCIPV_WITH_HW_MORE_THAN_HW_CONFIG<br \/>\nCIPV_WITH_LESS_THAN_HW_CONFIG<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-329\">\n\t<td class=\"column-1\">mobileye_hi_beam<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye high beam<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-330\">\n\t<td class=\"column-1\">mobileye_low_beam<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye low beam<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-331\">\n\t<td class=\"column-1\">mobileye_wipers<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye wipers<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-332\">\n\t<td class=\"column-1\">mobileye_right_signal<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye right signal<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-333\">\n\t<td class=\"column-1\">mobileye_left_signal<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye left signal<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-334\">\n\t<td class=\"column-1\">mobileye_brake_signal<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye brake signal<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-335\">\n\t<td class=\"column-1\">mobileye_wipers_available<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye wipers available<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-336\">\n\t<td class=\"column-1\">mobileye_low_beam_available<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye low beam available<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-337\">\n\t<td class=\"column-1\">mobileye_hi_beam_available<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye high beam available<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-338\">\n\t<td class=\"column-1\">mobileye_speed_available<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye speed available<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-339\">\n\t<td class=\"column-1\">mobileye_speed<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye speed<\/td><td class=\"column-5\">km\/h<\/td>\n<\/tr>\n<tr class=\"row-340\">\n\t<td class=\"column-1\">mobileye_tamper_alert<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye tamper alert<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-341\">\n\t<td class=\"column-1\">mobileye_tsr_enabled<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye TSR enabled<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-342\">\n\t<td class=\"column-1\">mobileye_tsr_warning_level<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye TSR warning level<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-343\">\n\t<td class=\"column-1\">mobileye_hw_repeat_enabled<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye headway warning repeat enabled<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-344\">\n\t<td class=\"column-1\">mobileye_vision_only_sign<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye vision only sign<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-345\">\n\t<td class=\"column-1\">mobileye_vision_only_supplementary_sign_type<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye vision only supplementary sign type<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-346\">\n\t<td class=\"column-1\">mobileye_sign_position_x<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye sign position X<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-347\">\n\t<td class=\"column-1\">mobileye_sign_position_y<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye sign position Y<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-348\">\n\t<td class=\"column-1\">mobileye_sign_position_z<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye sign position Z<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-349\">\n\t<td class=\"column-1\">mobileye_filter_type<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye filter type<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-350\">\n\t<td class=\"column-1\">mobileye_vision_sign_type_display_1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye vision sign type display 1<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-351\">\n\t<td class=\"column-1\">mobileye_vision_only_suplementary_sign_type_display_1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye vision only supplementary sign type display 1<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-352\">\n\t<td class=\"column-1\">mobileye_vision_sign_type_display_2<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye vision sign type display 2<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-353\">\n\t<td class=\"column-1\">mobileye_vision_only_suplementary_sign_type_display_2<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye vision only suplementary sign type display 2<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-354\">\n\t<td class=\"column-1\">mobileye_vision_sign_type_display_3<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye vision sign type display 3<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-355\">\n\t<td class=\"column-1\">mobileye_vision_only_suplementary_sign_type_display_3<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye vision only suplementary sign type display 3<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-356\">\n\t<td class=\"column-1\">mobileye_vision_sign_type_display_4<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye vision sign type display 4<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-357\">\n\t<td class=\"column-1\">mobileye_vision_only_suplementary_sign_type_display_4<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Mobileye vision only suplementary sign type display 4<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-358\">\n\t<td class=\"column-1\">obd_kline_dtc_and_mil<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD DTC and MIL<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-359\">\n\t<td class=\"column-1\">obd_kline_rpm<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD RPM<\/td><td class=\"column-5\">RPM<\/td>\n<\/tr>\n<tr class=\"row-360\">\n\t<td class=\"column-1\">obd_kline_vehicle_speed_sensor<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD vehicle speed<\/td><td class=\"column-5\">km\/h<\/td>\n<\/tr>\n<tr class=\"row-361\">\n\t<td class=\"column-1\">obd_kline_engine_coolant_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD engine coolant temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-362\">\n\t<td class=\"column-1\">obd_kline_ambient_air_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD ambient air temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-363\">\n\t<td class=\"column-1\">obd_kline_fuel_level_input<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD fuel level<\/td><td class=\"column-5\">%<\/td>\n<\/tr>\n<tr class=\"row-364\">\n\t<td class=\"column-1\">obd_kline_type_of_fuel<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD fuel type<br \/>\nPossible values:<br \/>\nNOT_AVAILABLE<br \/>\nGASOLINE<br \/>\nMETHANOL<br \/>\nETHANOL<br \/>\nDIESEL<br \/>\nLPG<br \/>\nCNG<br \/>\nPROPANE<br \/>\nELECTRIC<br \/>\nBIFUEL_RUNNING_GASOLINE<br \/>\nBIFUEL_RUNNING_METHANOL<br \/>\nBIFUEL_RUNNING_ETHANOL<br \/>\nBIFUEL_RUNNING_LPG<br \/>\nBIFUEL_RUNNING_CNG<br \/>\nBIFUEL_RUNNING_PROPANE<br \/>\nBIFUEL_RUNNING_ELECTRICITY<br \/>\nBIFUEL_RUNNING_ELECTRIC_AND_COMBUSTION_ENGINE<br \/>\nHYBRID_GASOLINE<br \/>\nHYBRID_ETHANOL<br \/>\nHYBRID_DIESEL<br \/>\nHYBRID_ELECTRIC<br \/>\nHYBRID_RUNNING_ELECTRIC_AND_COMBUSTION_ENGINE<br \/>\nHYBRID_REGENERATIVE<br \/>\nBIFUEL_DIESEL<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-365\">\n\t<td class=\"column-1\">obd_kline_engine_fuel_rate<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD engine fuel rate<\/td><td class=\"column-5\">l\/h<\/td>\n<\/tr>\n<tr class=\"row-366\">\n\t<td class=\"column-1\">obd_kline_actual_engine_percent_torque<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD actual engine percent torque<\/td><td class=\"column-5\">%<\/td>\n<\/tr>\n<tr class=\"row-367\">\n\t<td class=\"column-1\">obd_kline_distance_traveled_while_mil_is_activated<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD distance traveled while MIL is activated<\/td><td class=\"column-5\">km<\/td>\n<\/tr>\n<tr class=\"row-368\">\n\t<td class=\"column-1\">obd_kline_relative_accelerator_pedal_position<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD accelerator pedal position<\/td><td class=\"column-5\">%<\/td>\n<\/tr>\n<tr class=\"row-369\">\n\t<td class=\"column-1\">obd_kline_vin_1<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD VIN 1<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-370\">\n\t<td class=\"column-1\">obd_kline_vin_2<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD VIN 2<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-371\">\n\t<td class=\"column-1\">obd_kline_vin_3<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD VIN 3<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-372\">\n\t<td class=\"column-1\">obd_kline_time_since_engine_start<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD time since engine start<\/td><td class=\"column-5\">s<\/td>\n<\/tr>\n<tr class=\"row-373\">\n\t<td class=\"column-1\">obd_kline_dtc_counted<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OBD DTC count<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-374\">\n\t<td class=\"column-1\">satellite_messages_sent<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Satellite messages sent<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-375\">\n\t<td class=\"column-1\">pending_satellite_messages<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Pending satellite messages<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-376\">\n\t<td class=\"column-1\">spr_spreader_mode<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Spreader mode<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-377\">\n\t<td class=\"column-1\">spr_spreader_adjustment_of_simulation_driving_speed<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Spreader adjustment of simulation driving speed<\/td><td class=\"column-5\">km\/h<\/td>\n<\/tr>\n<tr class=\"row-378\">\n\t<td class=\"column-1\">spr_spreader_spreading_width<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Spreader spreading width<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-379\">\n\t<td class=\"column-1\">spr_spreading_solid_material_dosage_from_reservoir_1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Spreader spreading solid material dosage from reservoir 1<\/td><td class=\"column-5\">g\/m^2<\/td>\n<\/tr>\n<tr class=\"row-380\">\n\t<td class=\"column-1\">spr_spreading_brine_dosage<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Spreader spreading brine dosage<\/td><td class=\"column-5\">g\/m^2<\/td>\n<\/tr>\n<tr class=\"row-381\">\n\t<td class=\"column-1\">spr_spreader_maximum_button<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Spreader maximum button<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-382\">\n\t<td class=\"column-1\">spr_spread_solid_material_from_reservoir_1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Spreader spread solid material from reservoir 1<\/td><td class=\"column-5\">kg<\/td>\n<\/tr>\n<tr class=\"row-383\">\n\t<td class=\"column-1\">spr_spread_brine_material<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Spreader spread brine material<\/td><td class=\"column-5\">l<\/td>\n<\/tr>\n<tr class=\"row-384\">\n\t<td class=\"column-1\">spr_driven_length_while_spreading<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Spreader driven length while spreading<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-385\">\n\t<td class=\"column-1\">spr_driven_hours_while_spreading<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Spreader driven hours while spreading<\/td><td class=\"column-5\">h<\/td>\n<\/tr>\n<tr class=\"row-386\">\n\t<td class=\"column-1\">spr_error_code<\/td><td class=\"column-2\">Bitmap<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Spreader error code<br \/>\nPossible values:<br \/>\nRESERVED<br \/>\nNO_SALT <br \/>\nNO_BRINE <br \/>\nMIN_LEVEL_OF_TANK<br \/>\nMIN_LEVEL_OF_HOPPER<br \/>\nNO_FEEDBACK_FROM_SPINNER<br \/>\nNO_FEEDBACK_FROM_CONVEYER<br \/>\nNO_FEEDBACK_FROM_CONVEYER_2<br \/>\nNO_FEEDBACK_FROM_PUMP<br \/>\nSPINNER_RPM_OUT_OF_RANGE<br \/>\nCONVEYER_RPM_OUT_OF_RANGE<br \/>\nCONVEYER_2_RPM_OUT_OF_RANGE<br \/>\nPUMP_RPM_OUT_OF_RANGE<br \/>\nSETTING_OUT_OF_RANGE<br \/>\nAUX_ENGINE_CHARGE_CONTROL_FAULT<br \/>\nAUX_ENGINE_OIL_PRESSURE_TOO_LOW<br \/>\nAUX_ENGINE_WATER_TEMP_TOO_HIGH<br \/>\nRESERVED<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-387\">\n\t<td class=\"column-1\">spr_liquid_material<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Spreader liquid material<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-388\">\n\t<td class=\"column-1\">spr_solid_material<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Spreader solid material<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-389\">\n\t<td class=\"column-1\">driver_1_state<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Driver 1 state<br \/>\nPossible values:<br \/>\nREST<br \/>\nDRIVER_AVAILABLE<br \/>\nWORK<br \/>\nDRIVE<br \/>\nERROR<br \/>\nNOT_AVAILABLE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-390\">\n\t<td class=\"column-1\">driver_2_state<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Driver 2 state<br \/>\nPossible values:<br \/>\nREST<br \/>\nDRIVER_AVAILABLE<br \/>\nWORK<br \/>\nDRIVE<br \/>\nERROR<br \/>\nNOT_AVAILABLE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-391\">\n\t<td class=\"column-1\">tco_first_driver_state<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO first driver state<br \/>\nPossible values:<br \/>\nREST<br \/>\nDRIVER_AVAILABLE<br \/>\nWORK<br \/>\nDRIVE<br \/>\nERROR<br \/>\nNOT_AVAILABLE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-392\">\n\t<td class=\"column-1\">tco_second_driver_state<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO second driver state<br \/>\nPossible values:<br \/>\nREST<br \/>\nDRIVER_AVAILABLE<br \/>\nWORK<br \/>\nDRIVE<br \/>\nERROR<br \/>\nNOT_AVAILABLE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-393\">\n\t<td class=\"column-1\">tco_first_driver_card<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO first driver card<br \/>\nPossible values:<br \/>\nNOT_INSERTED<br \/>\nINSERTED<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-394\">\n\t<td class=\"column-1\">tco_second_driver_card<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO second driver card<br \/>\nPossible values:<br \/>\nNOT_INSERTED<br \/>\nINSERTED<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-395\">\n\t<td class=\"column-1\">tco_distance<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO distance<\/td><td class=\"column-5\">km<\/td>\n<\/tr>\n<tr class=\"row-396\">\n\t<td class=\"column-1\">tco_trip<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO trip distance<\/td><td class=\"column-5\">km<\/td>\n<\/tr>\n<tr class=\"row-397\">\n\t<td class=\"column-1\">tco_vehicle_speed<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO vehicle speed<\/td><td class=\"column-5\">km\/h<\/td>\n<\/tr>\n<tr class=\"row-398\">\n\t<td class=\"column-1\">tco_rpm<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO engine speed<\/td><td class=\"column-5\">RPM<\/td>\n<\/tr>\n<tr class=\"row-399\">\n\t<td class=\"column-1\">tco_registration_number<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO registration number<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-400\">\n\t<td class=\"column-1\">tacho_ddd_available<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Tacho card reader state<br \/>\nNOT_AVAILABLE<br \/>\nAVAILABLE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-401\">\n\t<td class=\"column-1\">tco_first_driver_driving_time_(prev_and_curr_week)<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO first driver driving time (prev. and curr. week)<\/td><td class=\"column-5\">min<\/td>\n<\/tr>\n<tr class=\"row-402\">\n\t<td class=\"column-1\">tco_second_driver_driving_time_(prev_and_curr_week)<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO second driver driving time (prev. and curr. week)<\/td><td class=\"column-5\">min<\/td>\n<\/tr>\n<tr class=\"row-403\">\n\t<td class=\"column-1\">tco_first_driver_duration_of_selected_activity<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO first driver duration of selected activity<\/td><td class=\"column-5\">min<\/td>\n<\/tr>\n<tr class=\"row-404\">\n\t<td class=\"column-1\">tco_second_driver_duration_of_selected_activity<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO second driver duration of selected activity<\/td><td class=\"column-5\">min<\/td>\n<\/tr>\n<tr class=\"row-405\">\n\t<td class=\"column-1\">tco_first_driver_continuous_driving_time<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO first driver continuous driving time<\/td><td class=\"column-5\">min<\/td>\n<\/tr>\n<tr class=\"row-406\">\n\t<td class=\"column-1\">tco_second_driver_continuous_driving_time<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO second driver continuous driving time<\/td><td class=\"column-5\">min<\/td>\n<\/tr>\n<tr class=\"row-407\">\n\t<td class=\"column-1\">tco_first_driver_cumulated_break_time<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO first driver accumulated break time<\/td><td class=\"column-5\">min<\/td>\n<\/tr>\n<tr class=\"row-408\">\n\t<td class=\"column-1\">tco_second_driver_cumulated_break_time<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO second driver accumulated break time<\/td><td class=\"column-5\">min<\/td>\n<\/tr>\n<tr class=\"row-409\">\n\t<td class=\"column-1\">tco_first_driver_time_related_states<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO first driver time related states<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-410\">\n\t<td class=\"column-1\">tco_second_driver_time_related_states<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO second driver time related states<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-411\">\n\t<td class=\"column-1\">tco_time<\/td><td class=\"column-2\">Datetime<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO tacho time<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-412\">\n\t<td class=\"column-1\">tco_can_tacho_time<\/td><td class=\"column-2\">Datetime<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">TCO CAN tacho Time<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-413\">\n\t<td class=\"column-1\">temperature_sensor_0<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Temperature sensor 0<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-414\">\n\t<td class=\"column-1\">temperature_sensor_1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Temperature sensor 1<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-415\">\n\t<td class=\"column-1\">temperature_sensor_2<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Temperature sensor 2<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-416\">\n\t<td class=\"column-1\">temperature_sensor_3<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Temperature sensor 3<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-417\">\n\t<td class=\"column-1\">temperature_sensor_0_id<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Temperature sensor 0 ID<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-418\">\n\t<td class=\"column-1\">temperature_sensor_1_id<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Temperature sensor 1 ID<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-419\">\n\t<td class=\"column-1\">temperature_sensor_2_id<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Temperature sensor 2 ID<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-420\">\n\t<td class=\"column-1\">temperature_sensor_3_id<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Temperature sensor 3 ID<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-421\">\n\t<td class=\"column-1\">ot_temperature_sensor_1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OT temperature sensor 1<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-422\">\n\t<td class=\"column-1\">ot_temperature_sensor_2<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OT temperature sensor 2<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-423\">\n\t<td class=\"column-1\">ot_temperature_sensor_3<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OT temperature sensor 3<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-424\">\n\t<td class=\"column-1\">ot_temperature_sensor_4<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OT temperature sensor 4<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-425\">\n\t<td class=\"column-1\">ot_temperature_sensor_5<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OT temperature sensor 5<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-426\">\n\t<td class=\"column-1\">ot_temperature_sensor_6<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">OT temperature sensor 6<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-427\">\n\t<td class=\"column-1\">bt_temperature_sensor_1<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">BT Temperature sensor 0<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-428\">\n\t<td class=\"column-1\">bt_temperature_sensor_2<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">BT Temperature sensor 1<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-429\">\n\t<td class=\"column-1\">bt_temperature_sensor_3<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">BT Temperature sensor 2<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-430\">\n\t<td class=\"column-1\">bt_temperature_sensor_4<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">BT Temperature sensor 3<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-431\">\n\t<td class=\"column-1\">bt_temperature_sensor_5<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">BT Temperature sensor 4<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-432\">\n\t<td class=\"column-1\">trailers_vehicle_abs_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers vehicle ABS status<br \/>\nPossible values:<br \/>\nPASSIVE<br \/>\nACTIVE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-433\">\n\t<td class=\"column-1\">trailers_vehicle_service_brake_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers vehicle service brake status<br \/>\nPossible values:<br \/>\nPASSIVE<br \/>\nACTIVE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-434\">\n\t<td class=\"column-1\">trailers_vdc_active<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers VDC active<br \/>\nPossible values:<br \/>\nPASSIVE<br \/>\nACTIVE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-435\">\n\t<td class=\"column-1\">trailers_vehicle_electrical_supply_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers vehicle electrical supply status<br \/>\nPossible values:<br \/>\nINSUFFICIENT<br \/>\nSUFFICIENT<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-436\">\n\t<td class=\"column-1\">trailers_external_brake_request_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers external brake request status<br \/>\nNO_REQUEST<br \/>\nREQUEST_ACTIVE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-437\">\n\t<td class=\"column-1\">trailers_braking_via_electric_control_line_support<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers braking via electric control line support<br \/>\nPossible values:<br \/>\nNOT_SUPPORTED<br \/>\nSUPPORTED<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-438\">\n\t<td class=\"column-1\">trailers_electrical_supply_of_non_braking_system_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers electrical supply of non-braking system status<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-439\">\n\t<td class=\"column-1\">trailers_electrical_load_proportional_function_installation_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers electrical load proportional function installation status<br \/>\nPossible values:<br \/>\nNOT_INSTALLED<br \/>\nINSTALLED<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-440\">\n\t<td class=\"column-1\">trailers_vehicle_type<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers vehicle type<br \/>\nPossible values:<br \/>\nTOWED_VEHICLE<br \/>\nCONVERTED_DOLLY_AXLE_LSB<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-441\">\n\t<td class=\"column-1\">trailers_stop_lamps_request<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers stop lamps request<br \/>\nPossible values:<br \/>\nNO_REQUEST<br \/>\nREQUEST_ACTIVE<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-442\">\n\t<td class=\"column-1\">trailers_red_warning_signal_request<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers red warning signal request<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-443\">\n\t<td class=\"column-1\">trailers_amber_warning_signal_request<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers amber warning signal request<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-444\">\n\t<td class=\"column-1\">trailers_vehicle_pneumatic_supply_status<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers vehicle pneumatic supply status<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON <\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-445\">\n\t<td class=\"column-1\">trailers_braking_system_wheel_based_vehicle_speed<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers braking system wheel\u2013based vehicle speed<\/td><td class=\"column-5\">km\/h<\/td>\n<\/tr>\n<tr class=\"row-446\">\n\t<td class=\"column-1\">trailers_wheel_speed_difference_main_axle<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers wheel speed difference main axle<\/td><td class=\"column-5\">km\/h<\/td>\n<\/tr>\n<tr class=\"row-447\">\n\t<td class=\"column-1\">trailers_lateral_acceleration<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers lateral acceleration<\/td><td class=\"column-5\">m\/s^2<\/td>\n<\/tr>\n<tr class=\"row-448\">\n\t<td class=\"column-1\">trailers_axle_load_sum<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers axle load sum<\/td><td class=\"column-5\">kg<\/td>\n<\/tr>\n<tr class=\"row-449\">\n\t<td class=\"column-1\">trailers_pneumatic_supply_pressure<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers pneumatic supply pressure<\/td><td class=\"column-5\">kPa<\/td>\n<\/tr>\n<tr class=\"row-450\">\n\t<td class=\"column-1\">trailers_brake_cylinder_pressure_first_axle_left_wheel<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers brake cylinder pressure first axle, left wheel<\/td><td class=\"column-5\">kPa<\/td>\n<\/tr>\n<tr class=\"row-451\">\n\t<td class=\"column-1\">trailers_brake_cylinder_pressure_first_axle_right_wheel<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers brake cylinder pressure first axle, right wheel<\/td><td class=\"column-5\">kPa<\/td>\n<\/tr>\n<tr class=\"row-452\">\n\t<td class=\"column-1\">trailers_brake_cylinder_pressure_second_axle_left_wheel<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers brake cylinder pressure second axle, left wheel<\/td><td class=\"column-5\">kPa<\/td>\n<\/tr>\n<tr class=\"row-453\">\n\t<td class=\"column-1\">trailers_brake_cylinder_pressure_second_axle_right_wheel<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers brake cylinder pressure second axle, right wheel<\/td><td class=\"column-5\">kPa<\/td>\n<\/tr>\n<tr class=\"row-454\">\n\t<td class=\"column-1\">trailers_brake_cylinder_pressure_third_axle_left_wheel<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers brake cylinder pressure third axle, left wheel<\/td><td class=\"column-5\">kPa<\/td>\n<\/tr>\n<tr class=\"row-455\">\n\t<td class=\"column-1\">trailers_brake_cylinder_pressure_third_axle_right_wheel<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers brake cylinder pressure third axle, right wheel<\/td><td class=\"column-5\">kPa<\/td>\n<\/tr>\n<tr class=\"row-456\">\n\t<td class=\"column-1\">trailers_high_resolution_vehicle_distance<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers high resolution vehicle distance<\/td><td class=\"column-5\">km<\/td>\n<\/tr>\n<tr class=\"row-457\">\n\t<td class=\"column-1\">trailers_service_distance<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Trailers service distance<\/td><td class=\"column-5\">km<\/td>\n<\/tr>\n<tr class=\"row-458\">\n\t<td class=\"column-1\">wireless_enabled<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Wireless enabled<br \/>\nPossible values:<br \/>\nDISABLED<br \/>\nENABLED<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-459\">\n\t<td class=\"column-1\">wireless_pair<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Wireless pair<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-460\">\n\t<td class=\"column-1\">wireless_driver_id<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Wireless driver ID<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-461\">\n\t<td class=\"column-1\">current_profile<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Current profile<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-462\">\n\t<td class=\"column-1\">power_supply_voltage<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Power supply voltage<\/td><td class=\"column-5\">V<\/td>\n<\/tr>\n<tr class=\"row-463\">\n\t<td class=\"column-1\">battery_voltage<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Battery voltage<\/td><td class=\"column-5\">V<\/td>\n<\/tr>\n<tr class=\"row-464\">\n\t<td class=\"column-1\">pcb_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">PCB temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-465\">\n\t<td class=\"column-1\">virtual_odometer<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Virtual odometer<\/td><td class=\"column-5\">km<\/td>\n<\/tr>\n<tr class=\"row-466\">\n\t<td class=\"column-1\">input_trigger<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Input trigger<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-467\">\n\t<td class=\"column-1\">priority<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Priority<br \/>\nPossible values:<br \/>\nLOW<br \/>\nHIGH<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-468\">\n\t<td class=\"column-1\">battery_current<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Battery charge current<\/td><td class=\"column-5\">mA<\/td>\n<\/tr>\n<tr class=\"row-469\">\n\t<td class=\"column-1\">movement<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Movement sensor<br \/>\nPossible values:<br \/>\nSTILL<br \/>\nMOVING<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-470\">\n\t<td class=\"column-1\">hdop<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">HDOP<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-471\">\n\t<td class=\"column-1\">modem_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Modem temperature<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-472\">\n\t<td class=\"column-1\">virtual_odometer_diff<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Virtual odometer DIFF<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-473\">\n\t<td class=\"column-1\">ignition_plugtrack<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Virtual ignition<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-474\">\n\t<td class=\"column-1\">sleep_timer<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Sleep timer<br \/>\nPossible values:<br \/>\nNO_EVENT<br \/>\nDEVICE_WAKE_UP_BY_TIMER_EVENT<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-475\">\n\t<td class=\"column-1\">custom_ignition<\/td><td class=\"column-2\">Enum<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Custom ignition<br \/>\nPossible values:<br \/>\nOFF<br \/>\nON<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-476\">\n\t<td class=\"column-1\">panic<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Panic status<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-477\">\n\t<td class=\"column-1\">shock_duration<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Shock duration<\/td><td class=\"column-5\">ms<\/td>\n<\/tr>\n<tr class=\"row-478\">\n\t<td class=\"column-1\">roll_over_alarm<\/td><td class=\"column-2\">Boolean<\/td><td class=\"column-3\">device_inputs<\/td><td class=\"column-4\">Rollover alarm<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-479\">\n\t<td class=\"column-1\">position<\/td><td class=\"column-2\">Array<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">Container for all record GPS parameters<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-480\">\n\t<td class=\"column-1\">altitude<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">position<\/td><td class=\"column-4\">Altitude<\/td><td class=\"column-5\">m<\/td>\n<\/tr>\n<tr class=\"row-481\">\n\t<td class=\"column-1\">longitude<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">position<\/td><td class=\"column-4\">Longitude<\/td><td class=\"column-5\">Degrees<\/td>\n<\/tr>\n<tr class=\"row-482\">\n\t<td class=\"column-1\">latitude<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">position<\/td><td class=\"column-4\">Latitude<\/td><td class=\"column-5\">Degrees<\/td>\n<\/tr>\n<tr class=\"row-483\">\n\t<td class=\"column-1\">direction<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">position<\/td><td class=\"column-4\">Direction<\/td><td class=\"column-5\">Degrees<\/td>\n<\/tr>\n<tr class=\"row-484\">\n\t<td class=\"column-1\">satellites_count<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">position<\/td><td class=\"column-4\">Satellites count<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-485\">\n\t<td class=\"column-1\">speed<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">position<\/td><td class=\"column-4\">Speed<\/td><td class=\"column-5\">km\/h<\/td>\n<\/tr>\n<tr class=\"row-486\">\n\t<td class=\"column-1\">address<\/td><td class=\"column-2\">Array<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">Container for all address components<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-487\">\n\t<td class=\"column-1\">country<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">address<\/td><td class=\"column-4\">Country name<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-488\">\n\t<td class=\"column-1\">country_code<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">address<\/td><td class=\"column-4\">Country code<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-489\">\n\t<td class=\"column-1\">county<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">address<\/td><td class=\"column-4\">County name<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-490\">\n\t<td class=\"column-1\">region<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">address<\/td><td class=\"column-4\">Region name<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-491\">\n\t<td class=\"column-1\">locality<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">address<\/td><td class=\"column-4\">Locality name<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-492\">\n\t<td class=\"column-1\">street<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">address<\/td><td class=\"column-4\">Street name<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-493\">\n\t<td class=\"column-1\">house_number<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">address<\/td><td class=\"column-4\">House number<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-494\">\n\t<td class=\"column-1\">zip<\/td><td class=\"column-2\">String<\/td><td class=\"column-3\">address<\/td><td class=\"column-4\">ZIP code<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-495\">\n\t<td class=\"column-1\">geozone_ids<\/td><td class=\"column-2\">Array<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">Container for all geozones IDs<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-496\">\n\t<td class=\"column-1\">tires<\/td><td class=\"column-2\">Array<\/td><td class=\"column-3\">inputs<\/td><td class=\"column-4\">Container for TPMS parameters received from device<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-497\">\n\t<td class=\"column-1\">tireXX<\/td><td class=\"column-2\">Array<\/td><td class=\"column-3\">tires<\/td><td class=\"column-4\">Container for tireXX received from hardware<br \/>\nXX goes from 01 to 36<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-498\">\n\t<td class=\"column-1\">tire_pressure_threshold_detection<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">tireXX<\/td><td class=\"column-4\">Signal indicating the pressure level of the tire.  The levels defined represent different pressure conditions of the tire:<br \/>\n000 Extreme over pressure - The tire pressure is at a level where the safety of the vehicle may be jeopardised.<br \/>\n001 Over pressure - The tire pressure is higher than the pressure defined by the vehicle or tire manufacturer.<br \/>\n010 No warning pressure - The tire pressure is within the thresholds defined by the vehicle or tire manufacturer.<br \/>\n011 Under pressure - The tire pressure is lower than the pressure defined by the vehicle or tire manufacturer.<br \/>\n100 Extreme under pressure - The tire pressure is at a level where the safety of the vehicle may be jeopardised.<br \/>\n101 Not defined<br \/>\n110 Error indicator<br \/>\n111 Not available<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-499\">\n\t<td class=\"column-1\">tire_sensor_electrical_fault<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">tireXX<\/td><td class=\"column-4\">Indicates the status of electrical fault on the tire sensor.<br \/>\n<br \/>\n00 Ok (No Fault)<br \/>\n01 Not Defined (Fault)<br \/>\n10 Error<br \/>\n11 Not Supported<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-500\">\n\t<td class=\"column-1\">tire_status<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">tireXX<\/td><td class=\"column-4\">Indicates the status of the tire.<br \/>\n<br \/>\n00 Ok (no fault)<br \/>\n01 Tire leak detected<br \/>\n10 Error<br \/>\n11 Not Supported<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-501\">\n\t<td class=\"column-1\">tire_temperature<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">tireXX<\/td><td class=\"column-4\">Temperature at the surface of the tire sidewall.<br \/>\nResolution: 0.03125 \u00b0C\/bit<br \/>\nOffset: 0<br \/>\nData Range: -273 to 1734.96875 \u00b0C<\/td><td class=\"column-5\">\u00b0C<\/td>\n<\/tr>\n<tr class=\"row-502\">\n\t<td class=\"column-1\">tire_air_leakage_rate<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">tireXX<\/td><td class=\"column-4\">The pressure loss rate of a tire.<br \/>\nResolution: 0.05 kPa\/bit<br \/>\nOffset: 0<br \/>\nData Range: 0 to 12.5 kPa<\/td><td class=\"column-5\">kPa<\/td>\n<\/tr>\n<tr class=\"row-503\">\n\t<td class=\"column-1\">tire_pressure<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">tireXX<\/td><td class=\"column-4\">Pressure at which air is contained in cavity formed by tire and rim.<br \/>\nResolution: 0.05 kPa\/bit<br \/>\nOffset: 0<br \/>\nData Range: 0 to 125 kPa<\/td><td class=\"column-5\">kPa<\/td>\n<\/tr>\n<tr class=\"row-504\">\n\t<td class=\"column-1\">tire_sensor_enable_status<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">tireXX<\/td><td class=\"column-4\">Indicates whether the tire sensor is being monitored by the controller or is Enabled\/Disabled.<br \/>\n<br \/>\n00 Off \/ Isolated \/ Disabled<br \/>\n01 On (tire is polled) \/ Enabled<br \/>\n10 Not Defined<br \/>\n11 Not Supported<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-505\">\n\t<td class=\"column-1\">tire_location<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">tireXX<\/td><td class=\"column-4\">Identifies which tire is associated with the parametric data in this PGN.<br \/>\n<br \/>\n The low order 4 bits represent a position number, counting left to right when facing in the direction of normal vehicle travel (forward).<br \/>\n The high order 4 bits represent a position number, counting front to back on the vehicle.<br \/>\n<br \/>\nThe value 0xFF indicates not available.<br \/>\n It is recommended that output devices add 1 to the position number (range 1 to 15, not 0 to 14) for use by drivers and service technicians.<br \/>\n Examples: Tire pressure for location 0x00 would be left front tire.<br \/>\n Tire pressure for location 0x23 would be right outside rear rear on a 3-axle tractor with dual axle per side (3rd axle, 4th tire).<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-506\">\n\t<td class=\"column-1\">tire_extended_tire_pressure_support<\/td><td class=\"column-2\">Number<\/td><td class=\"column-3\">tireXX<\/td><td class=\"column-4\">Defines the choice of using the tire pressure (PGN 65268) or Extended Tire Pressure (PGN 64578). The state value '01' indicates the extended tire pressure SPN is used for the pressure data. Any other value indicates the extended tire pressure SPN is not being used.<br \/>\n00 - Not Using Extended Tire Pressure<br \/>\n01 - Using Extended Tire Pressure<br \/>\n10 - Error<br \/>\n11 - Not Available\/Not Supported<\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-167 from cache -->\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n<h2 class=\"wp-block-heading\" id=\"tpms-data-support\">Podr\u0161ka za TPMS podatke<\/h2>\n\n<p>TPMS je kratica za Sustav za nadzor tlaka u gumama. Ruptela transportni telematski ure\u0111aji podr\u017eavaju TPMS prema dokumentaciji:   <\/p>\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/doc.ruptela.com\/articles\/#!accessories-publication\/tire-pressure-monitoring-system\" data-type=\"URL\" data-id=\"https:\/\/doc.ruptela.com\/articles\/#!accessories-publication\/tire-pressure-monitoring-system\">https:\/\/doc.ruptela.com\/articles\/#!accessories-publication\/tire-pressure-monitoring-system<\/a><\/li><\/ul>\n\n<p>Telematski podaci prikupljeni ure\u0111ajima putem konfiguriranih TPMS ulaza mogu se dohvatiti pomo\u0107u Object Coordinates History API v2 i v3. Prema zadanim postavkama, TPMS podaci se ne dodaju u API zahtjev i stoga ih treba omogu\u0107iti navo\u0111enjem dodatnog parametra u URL zahtjevu, konkretno: <\/p>\n\n<p style=\"background-color: #000000; color: #bbbdc0; font-family: Consolas; padding-left: 15px; padding-right: 15px;\">\n<br\/>\n&#038;include_tire_parameters=true\n<br\/>\n<br\/>\n<\/p>\n\n<p>Primjer API zahtjeva s uklju\u010denim TPMS podacima:<\/p>\n\n<p style=\"background-color: #000000; color: #bbbdc0; font-family: Consolas; padding-left: 10px; padding-right: 10px;\">\n<br\/>\nGET \/objects\/{objectId}\/coordinates?version=3&#038;api_key=<...>&#038;include_geozones=false&#038;from_datetime=2022-06-20T08:33:03.000Z&#038;to_datetime=2022-06-20T08:35:03.000Z&#038;include_tire_parameters=true<br\/>\nHost: api.fm-track.com<br\/>\nContent-Type: application\/json;charset=UTF-8 <br\/>\n<br\/>\n<\/p>\n\n<p>Primjer odgovora kada su uklju\u010deni TPMS podaci:<\/p>\n\n<div class=\"wp-block-codemirror-blocks-code-block code-block\"><pre class=\"CodeMirror\" data-setting=\"{&quot;mode&quot;:&quot;javascript&quot;,&quot;mime&quot;:&quot;application\/json&quot;,&quot;theme&quot;:&quot;dracula&quot;,&quot;lineNumbers&quot;:true,&quot;styleActiveLine&quot;:false,&quot;lineWrapping&quot;:false,&quot;readOnly&quot;:true,&quot;translatedWithWPMLTM&quot;:&quot;1&quot;,&quot;language&quot;:&quot;JSON&quot;,&quot;modeName&quot;:&quot;json&quot;}\">{\n    \"items\": [\n        {\n            \"object_id\": \"abc123\",\n            \"datetime\": \"2022-06-20T08:34:34.000Z\",\n            \"trip_type\": \"NONE\",\n            \"ignition_status\": \"OFF\",\n            \"position\": {\n                \"latitude\": 52.3411054,\n                \"longitude\": 21.4358205,\n                \"altitude\": 30,\n                \"direction\": 166,\n                \"speed\": 50,\n                \"satellites_count\": 13\n            },\n            \"address\": {\n                \"country\": \"Poland\",\n                \"country_code\": \"PL\",\n                \"county\": \"Masovian Voivodeship\",\n                \"region\": \"Wo\u0142omin County\",\n                \"locality\": \"Nowy Cyg\u00f3w\",\n                \"street\": \"\",\n                \"house_number\": \"\",\n                \"zip\": \"05-326\"\n            },\n            \"inputs\": {\n                \"other\": {\n                    \"country_code_geonames\": 227,\n                    \"virtual_gps_odometer\": 741.33\n                },\n                \"calculated_inputs\": {\n                    \"fuel_consumption\": 0.00,\n                    \"fuel_level\": 0.00,\n                    \"mileage\": 0.00,\n                    \"rpm\": 0.00,\n                    \"temperature\": 0.00,\n                    \"custom_input_1\": 0.00,\n                    \"custom_input_2\": 0.00,\n                    \"custom_input_3\": 0.00,\n                    \"custom_input_4\": 0.00,\n                    \"custom_input_5\": 0.00,\n                    \"custom_input_6\": 0.00,\n                    \"custom_input_7\": 0.00,\n                    \"custom_input_8\": 0.00,\n                    \"din1_working_time\": 0.00,\n                    \"din2_working_time\": 0.00,\n                    \"din3_working_time\": 0.00,\n                    \"din4_working_time\": 0.00,\n                    \"weight\": 0.00\n                },\n                \"device_inputs\": {\n                    \"input_trigger\": 0,\n                    \"priority\": \"LOW\",\n                    \"hdop\": \"0.0\"\n                },\n                \"tires\": {\n                    \"tire01\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2001.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire02\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2002.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire03\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2003.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire04\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2004.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire05\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2005.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire06\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2006.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire07\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2007.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire08\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2008.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire09\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2009.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire10\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2010.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire11\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2011.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire12\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2012.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire13\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2013.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire14\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2014.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire15\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2015.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire16\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2016.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire17\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2017.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire18\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2018.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire19\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2019.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire20\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2020.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire21\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2021.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire22\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2022.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire23\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2023.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire24\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2024.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire25\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2025.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire26\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2026.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire27\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2027.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire28\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2028.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire29\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2029.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire30\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2030.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire31\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2031.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire32\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2032.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire33\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2033.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire34\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2034.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire35\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2035.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    },\n                    \"tire36\": {\n                        \"tire_pressure_threshold_detection\": \"2\",\n                        \"tire_sensor_electrical_fault\": \"2\",\n                        \"tire_status\": \"1\",\n                        \"tire_temperature\": \"39.5\",\n                        \"tire_air_leakage_rate\": \"2036.0\",\n                        \"tire_pressure\": \"400\",\n                        \"tire_sensor_enable_status\": \"0\",\n                        \"tire_location\": \"23\",\n                        \"tire_extended_tire_pressure_support\": \"3\"\n                    }\n                }\n            }\n        }\n    ],\n    \"continuation_token\": null\n}<\/pre><\/div>\n\n<p><div class=\"alignleft\"><a href=\"https:\/\/www.fmsdocumentation.com\/hr\/apis\/api-za-povijest-koordinata-objekata\/\" title=\"API za povijest koordinata objekata\"><span class=\"arrow\">\u2039 &nbsp <\/span> API za povijest koordinata objekata <\/a><\/div> <div class=\"alignright\"><a href=\"https:\/\/www.fmsdocumentation.com\/hr\/apis\/api-za-povijest-koordinata-objekata-v2\/\" title=\"API za povijest koordinata objekata v2\">API za povijest koordinata objekata v2 <span class=\"arrow\"> &nbsp\u203a <\/span> <\/a><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bilje\u0161kaOvaj API nije uklju\u010den ni u jedan plan. Obratite se svom voditelju prodaje kako biste naru\u010dili i omogu\u0107ili ovaj API. Idi na odjeljke unutar ove stranice: Zahtjev za podatke za odre\u0111eni datum i vrijeme Zahtjev za podatke za odre\u0111eno razdoblje Podr\u0161ka za TPMS podatke API za povijest koordinata objekata koristi se za ispis povijesnih podataka &hellip; <a href=\"https:\/\/www.fmsdocumentation.com\/hr\/apis\/api-za-povijest-koordinata-objekata-v3\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">API za povijest koordinata objekata v3<\/span><\/a><\/p>\n","protected":false},"author":13,"featured_media":0,"parent":15069,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-14639","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.fmsdocumentation.com\/hr\/wp-json\/wp\/v2\/pages\/14639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmsdocumentation.com\/hr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fmsdocumentation.com\/hr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fmsdocumentation.com\/hr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fmsdocumentation.com\/hr\/wp-json\/wp\/v2\/comments?post=14639"}],"version-history":[{"count":1,"href":"https:\/\/www.fmsdocumentation.com\/hr\/wp-json\/wp\/v2\/pages\/14639\/revisions"}],"predecessor-version":[{"id":14652,"href":"https:\/\/www.fmsdocumentation.com\/hr\/wp-json\/wp\/v2\/pages\/14639\/revisions\/14652"}],"up":[{"embeddable":true,"href":"https:\/\/www.fmsdocumentation.com\/hr\/wp-json\/wp\/v2\/pages\/15069"}],"wp:attachment":[{"href":"https:\/\/www.fmsdocumentation.com\/hr\/wp-json\/wp\/v2\/media?parent=14639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}